{"id":99510,"date":"2024-08-05T21:55:39","date_gmt":"2024-08-06T00:55:39","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=99510"},"modified":"2024-08-05T21:55:41","modified_gmt":"2024-08-06T00:55:41","slug":"para-carlotto-maduro-es-un-dictador-que-esta-ofendiendo-la-memoria-de-chavez","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/08\/05\/para-carlotto-maduro-es-un-dictador-que-esta-ofendiendo-la-memoria-de-chavez\/","title":{"rendered":"Para Carlotto, Maduro es un \u00abdictador\u00bb que \u201cest\u00e1 ofendiendo\u201d la memoria de Ch\u00e1vez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta de Abuelas de Plaza de Mayo, Estela de Carlotto, consider\u00f3 que Maduro \u00abest\u00e1 realmente trampeando y no quiere moverse\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab<em><strong>Ha trampeado<\/strong><\/em>\u00ab. Con esas palabras, la presidenta de Abuelas de Plaza de Mayo, Estela de Carlotto, reconoci\u00f3 que las elecciones en Venezuela fueron fraudulentas y destac\u00f3 que el presidente Nicol\u00e1s Maduro \u00abser\u00e1 dictador\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las declaraciones las brind\u00f3 en una charla que mantuvo con Jorge Rial en Radio 10 donde aclar\u00f3 que se puede ser dictador aunque se llegue al poder con elecciones. \u00ab<strong><em>Ojal\u00e1 que se resuelva, porque no es f\u00e1cil, no es f\u00e1cil lo de Venezuela<\/em><\/strong>\u00ab, se\u00f1al\u00f3 Carlotto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego agreg\u00f3: \u00abEs un pa\u00eds donde tiene de arrastre lo que fue el fundador de ese partido pol\u00edtico. Y este hombre, ahora yo no tengo palabras para juzgarlo, porque no puedo hablar de lo que no s\u00e9. En esto tienen que estar los pol\u00edticos, pero los pa\u00edses tambi\u00e9n. Est\u00e1n condenando para que presente las actas pero se ve claramente que \u00e9l ha trampeado.&nbsp;<em><strong>Ser\u00e1 un dictador, de todas formas los ha habido y los habr\u00e1. Algunos est\u00e1n votados, pero son dictadores tambi\u00e9n<\/strong><\/em>\u00ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente expres\u00f3 de manera contundente que \u00ab\u00e9l est\u00e1 ofendiendo a la figura de Ch\u00e1vez\u00bb. \u00ab<em><strong>Est\u00e1 realmente trampeando y no quiere moverse y lo que \u00e9l pretende que va a decir no tiene c\u00f3mo. No tiene las boletas, no tiene nada.<\/strong><\/em>&nbsp;Yo lo estoy siguiendo porque, l\u00f3gicamente, a uno le interesan los pa\u00edses de Latinoam\u00e9rica\u00bb, concluy\u00f3 recordando que \u00ab<strong><em>la mayor\u00eda tuvimos dictaduras en el mismo momento, y todos perdieron familias<\/em><\/strong>\u00ab.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de Abuelas de Plaza de Mayo, Estela de Carlotto, consider\u00f3 que Maduro \u00abest\u00e1 realmente trampeando y no quiere moverse\u00bb. \u00abHa trampeado\u00ab. Con esas palabras, la presidenta de Abuelas de Plaza de Mayo, Estela de Carlotto, reconoci\u00f3 que las elecciones en Venezuela fueron fraudulentas y destac\u00f3 que el presidente Nicol\u00e1s Maduro \u00abser\u00e1 dictador\u00bb. Las &hellip;<\/p>\n","protected":false},"author":2,"featured_media":99511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14],"tags":[],"class_list":["post-99510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/08\/unnamed.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/99510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=99510"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/99510\/revisions"}],"predecessor-version":[{"id":99512,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/99510\/revisions\/99512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/99511"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=99510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=99510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=99510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}