{"id":97644,"date":"2024-07-03T18:51:39","date_gmt":"2024-07-03T21:51:39","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=97644"},"modified":"2024-07-03T18:51:40","modified_gmt":"2024-07-03T21:51:40","slug":"juicio-por-el-atentado-a-cfk-nicolas-carrizo-se-quebro-y-le-pidio-perdon-a-cristina-kirchner","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/07\/03\/juicio-por-el-atentado-a-cfk-nicolas-carrizo-se-quebro-y-le-pidio-perdon-a-cristina-kirchner\/","title":{"rendered":"Juicio por el atentado a CFK: Nicol\u00e1s Carrizo se quebr\u00f3 y le pidi\u00f3 perd\u00f3n a Cristina Kirchner"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Nicol\u00e1s Carrizo y Brenda Uliarte los dos acusados del ataque a la exvicepresidenta declararon en la segunda audiencia del juicio por el atentado a Cristina Kirchner.<\/strong>\u00a0La ex pareja de Sabag Montiel, se present\u00f3 a declarar en el Tribunal Oral Federal 6 (TOF 6), pero en el estrado\u00a0<strong>dijo que se sent\u00eda mal<\/strong>\u00a0y se retir\u00f3. Mientras que\u00a0<strong>Nicol\u00e1s Carrizo, se quebr\u00f3 a poco de empezar y pidi\u00f3 perd\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la segunda audiencia por el atentado a Cristina registrado en septiembre del 2022,\u00a0<strong>los dos acusados se presentaron a testificar.<\/strong>\u00a0Por un lado, Nicol\u00e1s Carrizo expres\u00f3 que:\u00a0<strong>\u00abNo tengo nada en contra de Cristina, jam\u00e1s matar\u00eda a una persona\u00bb.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El se\u00f1alado como \u00abjefe de los Copitos\u00bb, quebr\u00f3 a poco de empezar cuando record\u00f3 a la muerte de su pap\u00e1.\u00a0<strong>Luego en su declaraci\u00f3n plante\u00f3 que los mensajes en los que hablaba de matar pol\u00edticos eran \u00abun chiste\u00bb.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTodo siempre fue chiste, nunca me lo tom\u00e9 con la seriedad que ten\u00eda que ser y hace un a\u00f1o y nueve meses me castigo por eso, porque todo lo que dije nunca fue cierto, fue en joda, era nada m\u00e1s joder con el tema, nunca realmente me lo tom\u00e9 en serio\u00bb, se justific\u00f3 Carrizo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carrizo insisti\u00f3 que \u00abnunca\u00bb estuvo \u00abinvolucrado\u00bb en el atentado.<\/strong>&nbsp;\u00abNunca supe lo que iba a hacer \u00e9l, no sab\u00eda ni siquiera donde estaba ella. Todos los mensajes fueron joda porque fueron despu\u00e9s. Yo jam\u00e1s cruc\u00e9 un mensaje planificando nada, lo juro por dios\u00bb, dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicol\u00e1s Carrizo y Brenda Uliarte los dos acusados del ataque a la exvicepresidenta declararon en la segunda audiencia del juicio por el atentado a Cristina Kirchner.\u00a0La ex pareja de Sabag Montiel, se present\u00f3 a declarar en el Tribunal Oral Federal 6 (TOF 6), pero en el estrado\u00a0dijo que se sent\u00eda mal\u00a0y se retir\u00f3. Mientras que\u00a0Nicol\u00e1s &hellip;<\/p>\n","protected":false},"author":2,"featured_media":97645,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[639,50],"tags":[],"class_list":["post-97644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-judiciales"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/07\/a5b9009b03256a364171be3a162549bb.jpeg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/97644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=97644"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/97644\/revisions"}],"predecessor-version":[{"id":97646,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/97644\/revisions\/97646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/97645"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=97644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=97644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=97644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}