{"id":96082,"date":"2024-06-05T10:19:12","date_gmt":"2024-06-05T13:19:12","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=96082"},"modified":"2024-06-05T10:19:14","modified_gmt":"2024-06-05T13:19:14","slug":"biden-endurece-la-politica-migratoria-de-eeuu-con-una-orden-que-le-permitira-cerrar-la-frontera-con-mexico","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/06\/05\/biden-endurece-la-politica-migratoria-de-eeuu-con-una-orden-que-le-permitira-cerrar-la-frontera-con-mexico\/","title":{"rendered":"Biden endurece la pol\u00edtica migratoria de EEUU con una orden que le permitir\u00e1 cerrar la frontera con M\u00e9xico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Joe Biden endureci\u00f3 este martes la pol\u00edtica de inmigraci\u00f3n de los Estados Unidos con un decreto que restringe el asilo para los migrantes que buscan llegar al pa\u00eds cuando los cruces fronterizos ilegales superen los 2.500 diarios, una medida que intenta enfrentar una de las m\u00e1ximas preocupaciones de los estadounidenses y un tema clave de la campa\u00f1a presidencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La medida es la pol\u00edtica fronteriza m\u00e1s restrictiva instituida por Biden, o cualquier otro presidente dem\u00f3crata en la era moderna, y evoca a una iniciativa de 2018 del entonces presidente Donald Trump para cortar la migraci\u00f3n, que fue bloqueada en un tribunal federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una conferencia en la Casa Blanca, Biden dijo: \u00abDebemos enfrentar una verdad simple\u00bb. Y agreg\u00f3: \u00abPara proteger a Estados Unidos como una tierra que da la bienvenida a los inmigrantes, primero debemos asegurar la frontera y asegurarla ahora\u00bb, afirm\u00f3. Y dijo que tomaba esta medida porque en hab\u00eda fracasado este a\u00f1o en el Congreso una legislaci\u00f3n bipartidista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Joe Biden endureci\u00f3 este martes la pol\u00edtica de inmigraci\u00f3n de los Estados Unidos con un decreto que restringe el asilo para los migrantes que buscan llegar al pa\u00eds cuando los cruces fronterizos ilegales superen los 2.500 diarios, una medida que intenta enfrentar una de las m\u00e1ximas preocupaciones de los estadounidenses y un tema &hellip;<\/p>\n","protected":false},"author":2,"featured_media":96083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[],"class_list":["post-96082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/06\/migrantes-2.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/96082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=96082"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/96082\/revisions"}],"predecessor-version":[{"id":96084,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/96082\/revisions\/96084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/96083"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=96082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=96082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=96082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}