{"id":96050,"date":"2024-06-04T18:04:04","date_gmt":"2024-06-04T21:04:04","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=96050"},"modified":"2024-06-04T18:04:06","modified_gmt":"2024-06-04T21:04:06","slug":"un-jugador-se-llevo-89-282-206-de-pesos-en-la-poceada-y-es-oriundo-de-castelli","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/06\/04\/un-jugador-se-llevo-89-282-206-de-pesos-en-la-poceada-y-es-oriundo-de-castelli\/","title":{"rendered":"Un jugador se llev\u00f3 89.282.206 de pesos en la Poceada y es oriundo de Castelli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La ronda de ganadores de la Quiniela Poceada Chaque\u00f1a lleg\u00f3 hasta Juan Jos\u00e9 Castelli, ya que un matrimonio que reside en la zona c\u00e9ntrica de esta ciudad, logr\u00f3 sumar los cinco aciertos durante el sorteo del s\u00e1bado \u00faltimo, alz\u00e1ndose as\u00ed con un pozo cercano a los 90 millones de pesos.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Uno de los protagonistas de esta historia es un hombre de 54 a\u00f1os, que se desempe\u00f1a como empleado en un reconocido comercio gastron\u00f3mico de la zona.<\/strong>&nbsp;\u00abComo estaba trabajando, le ped\u00ed a mi se\u00f1ora que haga dos jugadas autom\u00e1ticas de la Poceada\u00bb, asever\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue la mujer quien se acerc\u00f3 personalmente hasta la Agencia 383 \u00abEl Buda\u00bb de V\u00edctor Morienega, ubicada en Sarmiento 45 de Castelli,&nbsp;<strong>para efectuar la jugada que terminar\u00eda siendo la \u00fanica ganadora del primer premio, durante la edici\u00f3n de la Poceada Chaque\u00f1a del s\u00e1bado 1 de junio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los n\u00fameros de la suerte fueron 06, 36, 52, 96 y 98.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNos enteramos esa misma noche\u00bb, revelaron los ganadores, a quienes&nbsp;<strong>este premio de 89.282.206 pesos les permitir\u00e1 cumplir con un sue\u00f1o de toda la vida: la anhelada casa propia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ronda de ganadores de la Quiniela Poceada Chaque\u00f1a lleg\u00f3 hasta Juan Jos\u00e9 Castelli, ya que un matrimonio que reside en la zona c\u00e9ntrica de esta ciudad, logr\u00f3 sumar los cinco aciertos durante el sorteo del s\u00e1bado \u00faltimo, alz\u00e1ndose as\u00ed con un pozo cercano a los 90 millones de pesos.&nbsp; Uno de los protagonistas de &hellip;<\/p>\n","protected":false},"author":2,"featured_media":74457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,3],"tags":[],"class_list":["post-96050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/04\/642c218e9c892275932427.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/96050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=96050"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/96050\/revisions"}],"predecessor-version":[{"id":96051,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/96050\/revisions\/96051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/74457"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=96050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=96050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=96050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}