{"id":95545,"date":"2024-05-27T17:11:19","date_gmt":"2024-05-27T20:11:19","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=95545"},"modified":"2024-05-27T17:11:22","modified_gmt":"2024-05-27T20:11:22","slug":"prepagas-proponen-devolver-en-12-cuotas-lo-que-cobraron-de-mas","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/05\/27\/prepagas-proponen-devolver-en-12-cuotas-lo-que-cobraron-de-mas\/","title":{"rendered":"Prepagas proponen devolver en 12 cuotas lo que cobraron de m\u00e1s"},"content":{"rendered":"\n<p>Las empresas de medicina prepaga propusieron este lunes devolver en 12 cuotas lo que le cobraron por encima de la inflaci\u00f3n a los afiliados desde diciembre \u00faltimo, seg\u00fan fuentes oficiales y privadas.<\/p>\n\n\n\n<p>Tambi\u00e9n, sugirieron dar de baja la investigaci\u00f3n por cartelizaci\u00f3n que comenz\u00f3 la Secretar\u00eda de Comercio y liberar los precios desde octubre en la audiencia convocada por la Justicia, con la participaci\u00f3n del Gobierno.<\/p>\n\n\n\n<p>\u201cLas prepagas unificaron una propuesta de devoluci\u00f3n de 12 cuotas de lo cobrado de m\u00e1s. La SSS est\u00e1 analiz\u00e1ndola pero hay voluntad de acuerdo. El tema que a esta hora lo que frena el acuerdo es que las 7 prepagas que est\u00e1n en la investigaci\u00f3n por cartelizaci\u00f3n de Comercio quieren que se caiga esa investigaci\u00f3n tambi\u00e9n\u201d, indicaron a Infobae fuentes que participan del encuentro que comenz\u00f3 a las 10 en el juzgado en lo civil y comercial federal Juan Rafael Stinco.<\/p>\n\n\n\n<p>La intenci\u00f3n de las empresas grandes es que se devuelva en 12 cuotas, ajustadas por el \u201c\u00cdndice de costos de Salud\u201d y, aprobado por la Resoluci\u00f3n 1293\/2022 del Ministerio de Salud, junto con el \u00cdndice de Remuneraci\u00f3n Imponible Promedio de los Trabajadores Estables (RIPTE), el tope previsto en el art\u00edculo 1\u00ba del Decreto N\u00ba743\/22 (90% de RIPTE) y el valor correspondiente a 6 salarios m\u00ednimos, vitales y m\u00f3viles, de conformidad con lo establecido en el Decreto 743\/2022 y la Resoluci\u00f3n 2577\/2022 de esa cartera.<\/p>\n\n\n\n<p>Adem\u00e1s, las prepagas propusieron un mecanismo para la indexaci\u00f3n de los pr\u00f3ximos meses, que, seg\u00fan el amparo presentado por la Superintendencia de Seguros de la Salud y la decisi\u00f3n de la Secretar\u00eda de Comercio, deb\u00eda ser por el \u00edndice de precios al consumidor (IPC) del Instituto Nacional de Estad\u00edstica y Censos (Indec).<\/p>\n\n\n\n<p>En este sentido, consideraron que la cuota de junio deber\u00eda ajustarse por el IPC y las correspondientes al per\u00edodo julio-septiembre por el 95% de ese mismo c\u00e1lculo, seg\u00fan detallaron fuentes privadas. As\u00ed, si la inflaci\u00f3n un mes es del 10%, aumentar\u00edan la cuota el 9,5%.<\/p>\n\n\n\n<p>Por otro lado, pretenden que desde octubre en adelante el Gobierno vuelva a liberar los precios del sector, de acuerdo al decreto dictado a fines del a\u00f1o pasado por el Poder Ejecutivo.<\/p>\n\n\n\n<p>Desde el Gobierno aclararon que \u201clas prepagas aumentaron hasta un 165% cuando el IPC fue del 114% y solo quieren devolver el 24%, nada m\u00e1s, y en 12 meses. Las prepagas se est\u00e1n quedando con la plata de sus usuarios. La propuesta de un 24% en 12 cuotas la SSS no la acepta\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las empresas de medicina prepaga propusieron este lunes devolver en 12 cuotas lo que le cobraron por encima de la inflaci\u00f3n a los afiliados desde diciembre \u00faltimo, seg\u00fan fuentes oficiales y privadas. Tambi\u00e9n, sugirieron dar de baja la investigaci\u00f3n por cartelizaci\u00f3n que comenz\u00f3 la Secretar\u00eda de Comercio y liberar los precios desde octubre en la &hellip;<\/p>\n","protected":false},"author":2,"featured_media":19917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[639,46],"tags":[],"class_list":["post-95545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-salud"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/01\/prepagas001.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/95545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=95545"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/95545\/revisions"}],"predecessor-version":[{"id":95546,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/95545\/revisions\/95546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/19917"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=95545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=95545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=95545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}