{"id":93962,"date":"2024-04-26T18:36:02","date_gmt":"2024-04-26T21:36:02","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=93962"},"modified":"2024-04-26T18:36:05","modified_gmt":"2024-04-26T21:36:05","slug":"enzo-fernandez-fue-operado-de-una-hernia-inguinal","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/04\/26\/enzo-fernandez-fue-operado-de-una-hernia-inguinal\/","title":{"rendered":"Enzo Fern\u00e1ndez fue operado de una hernia inguinal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Enzo Fern\u00e1ndez se someti\u00f3 una cirug\u00eda de hernia inguinal por decisi\u00f3n de los m\u00e9dicos del Chelsea. Esta situaci\u00f3n es observada por la Selecci\u00f3n argentina, que pretende contar con el volante para que dispute la Copa Am\u00e9rica de este a\u00f1o, que se jugar\u00e1 en los Estados Unidos del 20 de junio al 14 de julio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQuer\u00eda comunicarles que mi operaci\u00f3n se realiz\u00f3 con \u00e9xito, sali\u00f3 todo bien, gracias a Dios\u00bb, comenz\u00f3 el ex-River y detall\u00f3: \u00abNecesitaba hacerme esta cirug\u00eda, ya que ven\u00eda arrastrando el dolor por aproximadamente 6 meses. Era algo que pod\u00eda evitar mientras me trataba constantemente con inyecciones y medicamentos\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"481\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/04\/230954w850h481c.jpg.webp\" alt=\"\" class=\"wp-image-93963\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/04\/230954w850h481c.jpg.webp 850w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/04\/230954w850h481c.jpg-300x170.webp 300w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/04\/230954w850h481c.jpg-768x435.webp 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<br>Luego, el futbolista de la Albiceleste relat\u00f3: \u00abPero hace unas cuantas semanas el dolor empez\u00f3 a ser cada vez m\u00e1s intenso, sin que nada de esto haga efecto, y fue peor ya que entrenaba y jugaba con molestia, pero no quer\u00eda dejar de estar en los partidos que ten\u00eda. Cada vez que me toc\u00f3 jugar con la camiseta de Chelsea, como la de la Selecci\u00f3n, intente dar lo mejor de m\u00ed siempre pese a todo esto pero no lo soporte m\u00e1s\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al final, Enzo agradeci\u00f3 por todo el cari\u00f1o que recibi\u00f3 en estos d\u00edas y dej\u00f3 una promesa. \u00abGracias por los mensajes, el aliento y sus muestras de cari\u00f1o de siempre. Saludos para todos, les prometo que voy a volver m\u00e1s fuerte que nunca. Cu\u00eddense mucho\u00bb, cerr\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp; &nbsp;&nbsp;<br><strong>Cu\u00e1nto tiempo tardar\u00e1 Enzo Fern\u00e1ndez en recuperarse<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La recuperaci\u00f3n llevar\u00e1 entre tres a cuatro semanas, por lo que llegar\u00eda en condiciones para disputar la Copa Am\u00e9rica, inform\u00f3 el periodista de de TN Leo Paradizo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3mo es el grupo de Selecci\u00f3n argentina en la Copa Am\u00e9rica 2024<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La Selecci\u00f3n argentina conforma el grupo A de la Copa Am\u00e9rica junto a Per\u00fa, Chile y Canad\u00e1. El partido inaugural del certamen lo disputar\u00e1 la Albiceleste ante el pa\u00eds de Norteam\u00e9rica el 20 de junio a las 21 (hora de la Argentina) en el Mercedes Benz Stadium de Atlanta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enzo Fern\u00e1ndez se someti\u00f3 una cirug\u00eda de hernia inguinal por decisi\u00f3n de los m\u00e9dicos del Chelsea. Esta situaci\u00f3n es observada por la Selecci\u00f3n argentina, que pretende contar con el volante para que dispute la Copa Am\u00e9rica de este a\u00f1o, que se jugar\u00e1 en los Estados Unidos del 20 de junio al 14 de julio. \u00abQuer\u00eda &hellip;<\/p>\n","protected":false},"author":2,"featured_media":93964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[639,15],"tags":[],"class_list":["post-93962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-deportes"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/04\/30049dc3-2914-4282-9e4d-8cd4c535e16b.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/93962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=93962"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/93962\/revisions"}],"predecessor-version":[{"id":93965,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/93962\/revisions\/93965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/93964"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=93962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=93962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=93962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}