{"id":93513,"date":"2024-04-17T10:44:50","date_gmt":"2024-04-17T13:44:50","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=93513"},"modified":"2024-04-17T10:44:52","modified_gmt":"2024-04-17T13:44:52","slug":"sameep-reparo-las-canerias-sobre-la-ruta-11-y-el-rio-negro-de-resistencia","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/04\/17\/sameep-reparo-las-canerias-sobre-la-ruta-11-y-el-rio-negro-de-resistencia\/","title":{"rendered":"Sameep repar\u00f3 las ca\u00f1er\u00edas sobre la ruta 11 y el R\u00edo Negro de Resistencia"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Continuando con las respuestas inmediatas, desde Sameep se informa que se encuentran reparadas las ca\u00f1er\u00edas sobre la ruta 11 y el R\u00edo Negro de Resistencia, que hab\u00edan quedado inconclusas por la gesti\u00f3n anterior. Asimismo, se informa que se iniciar\u00e1n las maniobras de v\u00e1lvulas.<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vale recordar que&nbsp;<strong>estos inconvenientes se identificaron luego de que Sameep detectase una nueva rotura en una ca\u00f1er\u00eda de 250 mil\u00edmetros, a la altura del cruce de la ruta 11 y el r\u00edo Negro.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esto,&nbsp;<strong>los agentes intervinieron r\u00e1pidamente en la reparaci\u00f3n de estos conductos para recuperar el normal servicio en la zona Norte de Resistencia.<\/strong>&nbsp;No obstante, para aclarar que estas obras hidr\u00e1ulicas de la autov\u00eda en esta zona, ejecutadas por la gesti\u00f3n anterior, quedaron inconclusas en su momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n resulta indispensable hacer referencia que la empresa constructora que ten\u00eda a cargo la construcci\u00f3n de la Autov\u00eda dej\u00f3 el &nbsp;conducto apoyado sobre el r\u00edo, por lo que no est\u00e1 exento que la corriente o el carrizal lo pueden quebrar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras se ejecutaron los trabajos,&nbsp;<strong>hubo baja presi\u00f3n de agua en los barrios Seitor, Juan de Garay, Mapic, Aut\u00f3dromo, Parque Aut\u00f3dromo, Cristo Rey, Villa Gh\u00edo, Toba, Timb\u00f3, Villa Chica y las viviendas situadas detr\u00e1s del Mayorista Vital y Colonia Popular.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHay obras que no fueron ejecutadas de acuerdo a las normas de ingenier\u00eda, es decir que fueron realizadas sin cumplir las reglas correspondientes\u00bb, expres\u00f3 el gerente general de la empresa estatal, Edgardo Altamirano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo se hicieron las obras complementarias que realmente hab\u00eda que hacer; vamos arreglando y ejecutando las obras como corresponden\u00bb, finaliz\u00f3 Altamirano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuando con las respuestas inmediatas, desde Sameep se informa que se encuentran reparadas las ca\u00f1er\u00edas sobre la ruta 11 y el R\u00edo Negro de Resistencia, que hab\u00edan quedado inconclusas por la gesti\u00f3n anterior. Asimismo, se informa que se iniciar\u00e1n las maniobras de v\u00e1lvulas.&nbsp; Vale recordar que&nbsp;estos inconvenientes se identificaron luego de que Sameep detectase una &hellip;<\/p>\n","protected":false},"author":2,"featured_media":93514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,37],"tags":[],"class_list":["post-93513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/04\/164636w850h741c.jpg.webp","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/93513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=93513"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/93513\/revisions"}],"predecessor-version":[{"id":93515,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/93513\/revisions\/93515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/93514"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=93513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=93513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=93513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}