{"id":89001,"date":"2024-01-02T15:32:29","date_gmt":"2024-01-02T18:32:29","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=89001"},"modified":"2024-01-02T15:32:30","modified_gmt":"2024-01-02T18:32:30","slug":"milei-tildo-de-mentirosos-al-grupo-clarin","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/01\/02\/milei-tildo-de-mentirosos-al-grupo-clarin\/","title":{"rendered":"Milei tild\u00f3 de mentirosos al Grupo Clar\u00edn"},"content":{"rendered":"\n<p>El presidente<strong>\u00a0Javier Milei\u00a0<\/strong>public\u00f3 una dura cr\u00edtica contra Clar\u00edn, medio de comunicaci\u00f3n al que acus\u00f3 de estar\u00a0<strong>\u201cdistorsionando los hechos\u201d<\/strong>\u00a0por el titular y la autor\u00eda de unos videos publicados en la red social X.<\/p>\n\n\n\n<p>La publicaci\u00f3n en cuesti\u00f3n se titulaba<strong>\u00a0\u00abJavier Milei public\u00f3 videos de F\u00e1tima Florez ovacionada por el p\u00fablico en Mar del Plata\u00bb<\/strong>\u00a0y adjudicaba la fuente de los videos al Presidente<\/p>\n\n\n\n<p>En el video se pod\u00eda ver a la imitadora saludando a una multitud de personas desde la ventana del hotel donde se hospeda en Mar del Plata, mientras realiza la temporada de verano con su obra de teatro. Todo hab\u00eda sucedido en las primeras horas de A\u00f1o Nuevo cuando&nbsp;<strong>Florez salud\u00f3 a su p\u00fablico mientras los arengaba y agradec\u00eda.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"718\" height=\"749\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/01\/20240102_153143.png\" alt=\"\" class=\"wp-image-89002\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/01\/20240102_153143.png 718w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/01\/20240102_153143-288x300.png 288w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/figure>\n\n\n\n<p>La realidad es que, si bien los videos se compartieron desde la cuenta personal del Presidente,&nbsp;<strong>el mandatario no se encontraba en Mar del Plata&nbsp;<\/strong>sino que<strong>&nbsp;estaba realizando una videollamada con su pareja<\/strong>, tal como le indica la propia Florez al p\u00fablico, con tel\u00e9fono en mano.<\/p>\n\n\n\n<p>Por este motivo, a trav\u00e9s de su cuenta personal escribi\u00f3:<strong>&nbsp;\u00abPara variar @clarincom distorsionando (mintiendo) los hechos&#8230; Por suerte los argentinos ya despertaron y le sacaron la ficha&#8230;\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente\u00a0Javier Milei\u00a0public\u00f3 una dura cr\u00edtica contra Clar\u00edn, medio de comunicaci\u00f3n al que acus\u00f3 de estar\u00a0\u201cdistorsionando los hechos\u201d\u00a0por el titular y la autor\u00eda de unos videos publicados en la red social X. La publicaci\u00f3n en cuesti\u00f3n se titulaba\u00a0\u00abJavier Milei public\u00f3 videos de F\u00e1tima Florez ovacionada por el p\u00fablico en Mar del Plata\u00bb\u00a0y adjudicaba la fuente &hellip;<\/p>\n","protected":false},"author":2,"featured_media":89003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[639,14],"tags":[],"class_list":["post-89001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/01\/descarga-1.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/89001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=89001"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/89001\/revisions"}],"predecessor-version":[{"id":89004,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/89001\/revisions\/89004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/89003"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=89001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=89001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=89001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}