{"id":87155,"date":"2023-11-24T10:30:17","date_gmt":"2023-11-24T13:30:17","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=87155"},"modified":"2023-11-24T10:31:01","modified_gmt":"2023-11-24T13:31:01","slug":"una-ciclista-evito-que-un-motochorro-le-robe-poniendole-su-pie-en-la-rueda-de-la-moto","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/11\/24\/una-ciclista-evito-que-un-motochorro-le-robe-poniendole-su-pie-en-la-rueda-de-la-moto\/","title":{"rendered":"Una ciclista evit\u00f3 que un motochorro le robe poni\u00e9ndole su pie en la rueda de la moto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El hecho se dio este jueves por la tarde, a las 19:45, en avenida Espa\u00f1a y Ameghino de Barranqueras, donde un sujeto de 20 a\u00f1os, a bordo de una motocicleta, se acerc\u00f3 a una mujer que circulaba en una bicicleta, negra R-26, a la que quiso sustraerle la ri\u00f1onera que ten\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Motivo de esta acci\u00f3n, la ciclista de 44 a\u00f1os puso el pie en la rueda de la moto, lo que le caus\u00f3 la fractura de su pie izquierdo, pero tambi\u00e9n produjo la ca\u00edda del motociclista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo fue demorado por los vecinos de la zona, hasta el arribo de los efectivos policiales de la Comisar\u00eda Segunda de Barranqueras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La damnificada fue trasladada al Hospital Perrando para su atenci\u00f3n m\u00e9dica y el detenido alojado en la seccional, bajo la causa de \u00absupuesto robo en grado de tentativa y lesiones graves\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hecho se dio este jueves por la tarde, a las 19:45, en avenida Espa\u00f1a y Ameghino de Barranqueras, donde un sujeto de 20 a\u00f1os, a bordo de una motocicleta, se acerc\u00f3 a una mujer que circulaba en una bicicleta, negra R-26, a la que quiso sustraerle la ri\u00f1onera que ten\u00eda. Motivo de esta acci\u00f3n, &hellip;<\/p>\n","protected":false},"author":6,"featured_media":87156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,8],"tags":[],"class_list":["post-87155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-policiales"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/11\/bqueras.webp","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=87155"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87155\/revisions"}],"predecessor-version":[{"id":87157,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87155\/revisions\/87157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/87156"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=87155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=87155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=87155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}