{"id":8647,"date":"2020-07-03T21:03:09","date_gmt":"2020-07-04T00:03:09","guid":{"rendered":"http:\/\/portalmovil.com.ar\/?p=8647"},"modified":"2020-07-03T21:03:16","modified_gmt":"2020-07-04T00:03:16","slug":"gobierno-y-el-municipio-de-margarita-belen-acordaron-la-construccion-de-un-nuevo-registro-civil","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/07\/03\/gobierno-y-el-municipio-de-margarita-belen-acordaron-la-construccion-de-un-nuevo-registro-civil\/","title":{"rendered":"Gobierno y el municipio de Margarita Bel\u00e9n acordaron la construcci\u00f3n de un nuevo Registro Civil"},"content":{"rendered":"\n<p>El gobernador Jorge Capitanich y el intendente Javier Mart\u00ednez firmaron el convenio que permitir\u00e1 la construcci\u00f3n de un nuevo edificio para el registro civil en la localidad de Margarita Bel\u00e9n. Con una inversi\u00f3n de m\u00e1s de 8 millones de pesos, la obra, ser\u00e1 realizada mediante el trabajo en conjunto del Ministerio de Gobierno, a cargo de Juan Manuel Chapo, y del Ministerio de Infraestructura, a cargo de Juan Manuel Carreras.<\/p>\n\n\n\n<p>El nuevo edificio, permitir\u00e1 concentrar en un solo espacio todas las actividades que se realizan actualmente, optimizando la atenci\u00f3n al p\u00fablico y mejorando el funcionamiento interno de la instituci\u00f3n y de la inspector\u00eda laboral. Tras la firma, el ministro Juan Manuel Chapo se\u00f1al\u00f3 que el proyecto busca adem\u00e1s, reducir el gasto p\u00fablico destinado a alquileres de edificios para las distintas dependencias. \u201cSuplantar alquileres por infraestructura propia es una decisi\u00f3n estrat\u00e9gica del gobernador\u201d, sostuvo.<\/p>\n\n\n\n<p>Por su parte, el intendente de la localidad, Javier Mart\u00ednez indic\u00f3 que se trat\u00f3 de un d\u00eda hist\u00f3rico para Margarita en lo que tiene que ver con el inicio de la concreci\u00f3n de la obra. \u201cVamos a concretar un gran anhelo y una obra muy esperada por toda la comunidad. Es un d\u00eda hist\u00f3rico para Margarita Bel\u00e9n, estamos muy agradecidos por esta gesti\u00f3n\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El edificio<\/h3>\n\n\n\n<p>El edificio contar\u00e1 con dos sectores en planta baja para la circulaci\u00f3n de personas con discapacidad. En total ser\u00e1n 137 metros cuadrados con todas las comodidades necesarias. \u201cEstamos hablando de un edificio p\u00fablico de primer nivel que contar\u00e1 adem\u00e1s con un espacio de estacionamiento\u201d, ampli\u00f3 Chapo.<\/p>\n\n\n\n<p>El ministro detall\u00f3 que el 36% de la inversi\u00f3n ser\u00e1 llevada a cabo por el Ministerio de Gobierno, mientras que 64% restante ser\u00e1 un aporte con fondos propios del Ministerio de Infraestructura. \u201cActualmente son 98 los registros civiles con los que cuenta la provincia y por eso estamos trabajando fuertemente para desarrollar obras de construcci\u00f3n, refacci\u00f3n y ampliaci\u00f3n\u201d, destac\u00f3.<\/p>\n\n\n\n<p>La obra se sumar\u00e1 a los trabajos realizados en otros puntos de la provincia. \u201cEsta semana terminamos la refacci\u00f3n del registro civil en Santa Sylvina y pronto podremos inaugurar el registro civil de Lapachito. Tenemos obras avanzadas en Colonia Ben\u00edtez, Barranqueras y San Mart\u00edn\u201d, record\u00f3 Chapo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Jorge Capitanich y el intendente Javier Mart\u00ednez firmaron el convenio que permitir\u00e1 la construcci\u00f3n de un nuevo edificio para el registro civil en la localidad de Margarita Bel\u00e9n. Con una inversi\u00f3n de m\u00e1s de 8 millones de pesos, la obra, ser\u00e1 realizada mediante el trabajo en conjunto del Ministerio de Gobierno, a cargo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8648,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,14],"tags":[],"class_list":["post-8647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/07\/5eff968d8eb30965851400.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8647"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8647\/revisions"}],"predecessor-version":[{"id":8649,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8647\/revisions\/8649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/8648"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}