{"id":85244,"date":"2023-10-22T16:24:36","date_gmt":"2023-10-22T19:24:36","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=85244"},"modified":"2023-10-22T16:25:49","modified_gmt":"2023-10-22T19:25:49","slug":"leandro-zdero-no-es-lo-mismo-para-el-chaco-cualquiera-de-las-opciones-politicas","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/10\/22\/leandro-zdero-no-es-lo-mismo-para-el-chaco-cualquiera-de-las-opciones-politicas\/","title":{"rendered":"Leandro Zdero: \u201cNo es lo mismo para el Chaco cualquiera de las opciones pol\u00edticas\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobernador electo Leandro Zdero emiti\u00f3 su voto en horas de la ma\u00f1ana, en la ciudad de Resistencia y remarc\u00f3 que la jornada ser\u00e1 de monitoreo permanente .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, Zdero invit\u00f3 a los chaque\u00f1os a marcar su presencia en las urnas y cont\u00f3 que ya mantuvo \u00abcomunicaciones con gobernadores de diferentes provincias\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, asegur\u00f3 que hasta el momento se mantuvo una \u00abnormalidad en el desarrollo del acto electoral\u00bb y que espera que se mantenga de esa forma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto a los resultados, a\u00fan no defini\u00f3 si los esperar\u00e1 en Resistencia o Buenos Aires , y agreg\u00f3 que \u00abel escrutinio puede darse con celeridad pero hay que hacerlo de manera muy responsable\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, habl\u00f3 sobre un posible balotaje y asegur\u00f3 que depende de los argentinos. \u00abEn la provincia del Chaco muchos esperaban balotaje y se defini\u00f3 en primera vuelta\u00bb declar\u00f3. En esa misma l\u00ednea sentenci\u00f3 que \u00abno es lo mismo para el Chaco cualquiera de las opciones pol\u00edticas , por lo cu\u00e1l estamos muy atentos a esa responsabilidad\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador electo Leandro Zdero emiti\u00f3 su voto en horas de la ma\u00f1ana, en la ciudad de Resistencia y remarc\u00f3 que la jornada ser\u00e1 de monitoreo permanente . En este sentido, Zdero invit\u00f3 a los chaque\u00f1os a marcar su presencia en las urnas y cont\u00f3 que ya mantuvo \u00abcomunicaciones con gobernadores de diferentes provincias\u00bb. Tambi\u00e9n, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":85245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,14],"tags":[],"class_list":["post-85244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-politica"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/10\/394310552_897756738372693_3597120363245698289_n.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/85244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=85244"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/85244\/revisions"}],"predecessor-version":[{"id":85246,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/85244\/revisions\/85246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/85245"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=85244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=85244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=85244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}