{"id":83001,"date":"2023-09-14T16:42:26","date_gmt":"2023-09-14T19:42:26","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=83001"},"modified":"2023-09-14T16:42:29","modified_gmt":"2023-09-14T19:42:29","slug":"asistieron-a-un-nino-que-se-atraganto-con-un-chupetin-en-resistencia","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/09\/14\/asistieron-a-un-nino-que-se-atraganto-con-un-chupetin-en-resistencia\/","title":{"rendered":"Asistieron a un ni\u00f1o que se atragant\u00f3 con un chupet\u00edn en Resistencia"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Este mi\u00e9rcoles por la noche, se hizo presente en la Comisar\u00eda Novena, un hombre de 30 a\u00f1os con su hijo de 4, quien habr\u00eda tragado por accidente un chupet\u00edn y ten\u00eda obstruida la respiraci\u00f3n.<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Alrededor de las 21,&nbsp;<strong>los efectivos intervinieron de forma inmediata ante esta situaci\u00f3n y trasladaron al ni\u00f1o al Hospital Pedi\u00e1trico<\/strong>, donde fue intervenido r\u00e1pidamente por los m\u00e9dicos de guardia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momentos despu\u00e9s, los polic\u00edas fueron informados que&nbsp;<strong>el ni\u00f1o estaba fuera de riesgo, gracias a la r\u00e1pida intervenci\u00f3n policial para su traslado al hospital y al trabajo del personal de la salud.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente,&nbsp;<strong>el ni\u00f1o de 4 a\u00f1os fue dado de alta y regres\u00f3 a su hogar con sus padres.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles por la noche, se hizo presente en la Comisar\u00eda Novena, un hombre de 30 a\u00f1os con su hijo de 4, quien habr\u00eda tragado por accidente un chupet\u00edn y ten\u00eda obstruida la respiraci\u00f3n.&nbsp; Alrededor de las 21,&nbsp;los efectivos intervinieron de forma inmediata ante esta situaci\u00f3n y trasladaron al ni\u00f1o al Hospital Pedi\u00e1trico, donde fue &hellip;<\/p>\n","protected":false},"author":2,"featured_media":83002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,37],"tags":[],"class_list":["post-83001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/09\/159920w850h576c.jpg.webp","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/83001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=83001"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/83001\/revisions"}],"predecessor-version":[{"id":83003,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/83001\/revisions\/83003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/83002"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=83001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=83001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=83001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}