{"id":82795,"date":"2023-09-12T09:59:50","date_gmt":"2023-09-12T12:59:50","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=82795"},"modified":"2023-09-12T09:59:55","modified_gmt":"2023-09-12T12:59:55","slug":"queria-vender-un-arma-y-termino-detenido","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/09\/12\/queria-vender-un-arma-y-termino-detenido\/","title":{"rendered":"Quer\u00eda vender un arma y termin\u00f3 detenido"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta madrugada los efectivos recibieron el aviso de que en cercan\u00edas del Polideportivo Jaime Zapata un hombre de 43 a\u00f1os quer\u00eda comercializar un revolver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alrededor de las 3 de la ma\u00f1ana, los agentes policiales circulaban por Avenida Malvinas Argentinas y Mac Lean, all\u00ed transe\u00fantes dieron aviso de dicha situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esto los agentes se dirigieron Calle Capit\u00e1n Giacchino y Malvinas Argentinas, donde vieron a un hombre de similares caracter\u00edsticas a las descriptas por las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es as\u00ed que lo demoraron y requisaron, ten\u00eda en su poder un revolver calibre 32 pavonado gris de siete alveolos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, conforme lo dispuesto por la magistratura en turno el demorado fue notificado de su detenci\u00f3n en una causa por \u00abSupuesta Infracci\u00f3n al C\u00f3digo 189\u00b0 Bis del C\u00f3digo Penal Argentino\u00bb, y entregado a la Comisaria Sexta donde fue alojado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta madrugada los efectivos recibieron el aviso de que en cercan\u00edas del Polideportivo Jaime Zapata un hombre de 43 a\u00f1os quer\u00eda comercializar un revolver.<\/p>\n","protected":false},"author":6,"featured_media":82797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,37],"tags":[],"class_list":["post-82795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/09\/Resistencia-6.webp","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=82795"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82795\/revisions"}],"predecessor-version":[{"id":82798,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82795\/revisions\/82798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/82797"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=82795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=82795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=82795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}