{"id":8100,"date":"2020-06-23T17:23:02","date_gmt":"2020-06-23T20:23:02","guid":{"rendered":"http:\/\/portalmovil.com.ar\/?p=8100"},"modified":"2020-06-24T00:19:20","modified_gmt":"2020-06-24T03:19:20","slug":"fallecio-el-subcomisario-pogonza-contagiado-por-la-funcionaria-nacional-en-el-sauzalito","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/06\/23\/fallecio-el-subcomisario-pogonza-contagiado-por-la-funcionaria-nacional-en-el-sauzalito\/","title":{"rendered":"Falleci\u00f3 el subcomisario Pogonza, contagiado por la funcionaria nacional en El Sauzalito"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A comienzos de junio, el Gobernador Jorge Capitanich, junto a parte de su Gabinete y la titular del INAI (Instituto Nacional de Asuntos Ind\u00edgenas), Magdalena Odarga, visitaron localidades del Norte chaque\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edas despu\u00e9s se hizo de p\u00fablico conocimiento que tanto la presidente del INAI como la Ministra de Seguridad y las secretarias de Ambiente y de Desarrollo Social dieron positivo a Coronavirus. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta tarde, el Subcomisario Ren\u00e9 Eugenio Pogonza falleci\u00f3 con COVID-19 Positivo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/06\/23506353f0c2be5422abb582c8f40f41ce1657fa.jpg\" alt=\"\" class=\"wp-image-8115\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/06\/23506353f0c2be5422abb582c8f40f41ce1657fa.jpg 400w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/06\/23506353f0c2be5422abb582c8f40f41ce1657fa-150x150.jpg 150w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/06\/23506353f0c2be5422abb582c8f40f41ce1657fa-300x300.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El efectivo prestaba servicio en la localidad de El Sauzalito, ten\u00eda otras patolog\u00edas de base complicada por el Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras varios d\u00edas de agon\u00eda y a pesar de todas las pr\u00e1cticas para salvarle la vida \u2013 hace dos d\u00edas hab\u00edan iniciado con \u00e9l un tratamiento de plasmas- dej\u00f3 de existir &nbsp;cerca de las 16hs en el hospital del Bicentenario de Juan Jos\u00e9 Castelli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A comienzos de junio, el Gobernador Jorge Capitanich, junto a parte de su Gabinete y la titular del INAI (Instituto Nacional de Asuntos Ind\u00edgenas), Magdalena Odarga, visitaron localidades del Norte chaque\u00f1o. D\u00edas despu\u00e9s se hizo de p\u00fablico conocimiento que tanto la presidente del INAI como la Ministra de Seguridad y las secretarias de Ambiente y &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[42,8],"tags":[],"class_list":["post-8100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interior","category-policiales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/06\/34fd9788f2d3348bd84d989903aeb5916c4955d9.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8100"}],"version-history":[{"count":2,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8100\/revisions"}],"predecessor-version":[{"id":8116,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/8100\/revisions\/8116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/8124"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}