{"id":77155,"date":"2023-06-02T10:36:26","date_gmt":"2023-06-02T13:36:26","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=77155"},"modified":"2023-06-02T10:36:30","modified_gmt":"2023-06-02T13:36:30","slug":"martinez-entrego-juegos-de-camisetas-y-elementos-deportivos-al-club-lujan-es-fundamental-apoyar-al-deporte-social","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/06\/02\/martinez-entrego-juegos-de-camisetas-y-elementos-deportivos-al-club-lujan-es-fundamental-apoyar-al-deporte-social\/","title":{"rendered":"Mart\u00ednez entreg\u00f3 juegos de camisetas y elementos deportivos al Club Luj\u00e1n: \u00abEs fundamental apoyar al deporte social\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gustavo Mart\u00ednez entreg\u00f3 indumentaria y elementos deportivos a los m\u00e1s de 400 chicos que asisten al Club Deportivo Lujan, situado en avenida Martina al 1400 en Villa R\u00edo Negro, y que fue cuna de Claudio \u00abDiablito\u00bb Echeverri, actual promesa de River.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La instituci\u00f3n recibi\u00f3 440 kits compuestos por 11 juegos de 20 camisetas y 20 pantalones cada uno, y tambi\u00e9n le fueron otorgadas 20 pelotas, 20 conos, 20 aros, 20 tortuguitas, 2 vallas y 2 escaleras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsta acci\u00f3n se logr\u00f3 gracias al Registro Municipal de Clubes de Barrio que tiene el objetivo de fomentar el deporte social desde una planificaci\u00f3n de trabajo que se acople con otros programas comunales y acciones dirigidas a las infancias y juventudes. El registro contin\u00faa abierto para los interesados, que pueden hacer sus consultas en el Consejo Consultivo del Deporte situado en Jos\u00e9 Hern\u00e1ndez al 236\u00bb, detallaron desde el Municipio de Resistencia.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00abAPOYO AL DEPORTE SOCIAL\u00bb<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gustavo Mart\u00ednez sostuvo que \u00abse sigue dando cumplimiento a la ordenanza municipal de clubes de barrio, que ya permiti\u00f3 registrar m\u00e1s de 170 instituciones de la ciudad, y donde se prev\u00e9 que todos los a\u00f1os la gesti\u00f3n municipal pueda entregar indumentaria deportiva y elementos deportivos a las entidades\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una l\u00ednea semejante, indic\u00f3 que \u00abla situaci\u00f3n econ\u00f3mica actual es complicada, pero aun en ese contexto adverso estos clubes crecieron mucho gracias al respaldo de los padres y madres de la comunidad, y al trabajo incansable de los profesores\u00bb, y agreg\u00f3 que \u00aben ese marco, es fundamental apoyar el deporte social porque es un gran formador y moderador de valores\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CLUBES DE BARRIO<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, remarc\u00f3 que \u00abdel Deportivo Luj\u00e1n sali\u00f3 el \u2018Diablito\u2019 Echeverri que jug\u00f3 la Copa Futuro y que tiene una carrera m\u00e1s que promisoria por su talento, capacidad, disciplina y esfuerzo\u00bb, y ampli\u00f3 diciendo que \u00abes muy importante que todos los adolescentes y j\u00f3venes sepan que las metas se logran a partir del esfuerzo y el entrenamiento\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En igual sentido, consider\u00f3 que \u00ablos clubes de barrio generan oportunidades para muchos atletas como Echeverry, y tambi\u00e9n permiten desarrollar valores desde la integraci\u00f3n de los chicos y chicas y las familias\u00bb, y a\u00f1adi\u00f3 que \u00ablos ni\u00f1os y ni\u00f1as aprenden a trabajar y jugar en equipo, aprenden a respetar reglas y a las autoridades que los gu\u00edan\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El coordinador del f\u00fatbol de Deportivo de Luj\u00e1n, el profesor F\u00e9lix Garc\u00eda, expres\u00f3 que \u00abla alegr\u00eda de recibir estos elementos deportivos se manifest\u00f3 en la cara de los chicos, sobre todo en clubes como este donde todo cuesta y es esencial contar con el apoyo de la gesti\u00f3n municipal\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, detall\u00f3 que \u00abeste club tiene apenas 15 a\u00f1os, y actualmente asisten alrededor de 400 chicos y chicas divididos en 10 divisiones formativas, m\u00e1s hockey y handball\u00bb, y continu\u00f3 aseverando que \u00abla figura que refleja el esfuerzo de esta instituci\u00f3n es el \u2018Diablito\u2019 Echeverri, que es la muestra de que se puede desde un club de barrio dar el gran salto con trabajo y con talento\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ariel Fleitas es pap\u00e1 de Thiago que juega en la 9\u00aa divisi\u00f3n, y coment\u00f3 que \u00abgracias al club se conocen amigos y se palpan las realidades que hay alrededor, por eso es importante la ayuda en lo deportivo y en lo social a una instituci\u00f3n como esta\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Miriam Beatriz Garc\u00eda tiene una hija jugando hockey, y se\u00f1al\u00f3 que \u00abvenir al club y compartir con amigos, con padres, con profesores ense\u00f1a cosas buenas\u00bb, y finaliz\u00f3 asegurando que \u00abel apoyo de la gesti\u00f3n municipal es importante porque hay chicos que no pueden y no tienen para comprar indumentaria deportiva\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gustavo Mart\u00ednez entreg\u00f3 indumentaria y elementos deportivos a los m\u00e1s de 400 chicos que asisten al Club Deportivo Lujan, situado en avenida Martina al 1400 en Villa R\u00edo Negro, y que fue cuna de Claudio \u00abDiablito\u00bb Echeverri, actual promesa de River. La instituci\u00f3n recibi\u00f3 440 kits compuestos por 11 juegos de 20 camisetas y 20 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":77156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,37],"tags":[],"class_list":["post-77155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/06\/576423w850h567c.jpg.webp","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=77155"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77155\/revisions"}],"predecessor-version":[{"id":77157,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77155\/revisions\/77157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/77156"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=77155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=77155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=77155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}