{"id":7708,"date":"2020-06-14T01:11:44","date_gmt":"2020-06-14T04:11:44","guid":{"rendered":"http:\/\/portalmovil.com.ar\/?p=7708"},"modified":"2020-06-14T01:11:49","modified_gmt":"2020-06-14T04:11:49","slug":"policias-en-un-operativo-cerrojo-recuperaron-una-camioneta-robada","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/06\/14\/policias-en-un-operativo-cerrojo-recuperaron-una-camioneta-robada\/","title":{"rendered":"Polic\u00edas en un operativo cerrojo recuperaron una camioneta robada"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Anoche, alrededor de las 20:30 personal de la Divisi\u00f3n Transito Urbano y Seguridad Vial de la termal inicio a diversos operativos cerrojos, cercando las rutas y caminos vecinales con la finalidad de detener a los presuntos autores y al recupero del rodado, que horas despu\u00e9s fue hallado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es as\u00ed que &nbsp;en el puesto de control de Ruta 95 Km., 1109 detr\u00e1s del Zool\u00f3gico, a las 22, observan a una motocicleta que se dirig\u00eda hacia el ret\u00e9n, notando que descienden dos sujetos, a los que demoran r\u00e1pidamente y el conductor del motovehiculo huye.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los demorados, ambos de 27 a\u00f1os, ten\u00edan en su poder un gato hidr\u00e1ulico completo marca Hilux\/Fortuner, con todos sus accesorios, envuelto en su estuche original de color negro y un cuchillo por la cual se procede hacer traslado de estos individuos hasta Medicina legal y secuestros de estos elementos que presumiblemente interesar\u00eda en la causa de Hurto Automotor, hasta la Unidad a fines realizar correspondiente Informe judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Minutos despu\u00e9s de esto, se present\u00f3 en la Guardia de Prevenci\u00f3n de la Divisi\u00f3n, el damnificado por el robo de la camioneta, quien reconoces los elementos secuestrados como perteneciente al rodado.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n al preguntarle a los conducidos&nbsp; estos manifiestan de forma voluntaria indican donde estaba escondido el veh\u00edculo robado, el cual fue hallado escondido en Ruta 95&nbsp; km. 1005 a unos 100 metros del acceso Club Democr\u00e1tico espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consultado Fiscal\u00eda Investigaci\u00f3n en Turno N\u00b0 3, dispuso el secuestro del rodado, previa pericia de la Divisi\u00f3n Criminal\u00edstica y la conducci\u00f3n de los dos individuos junto a la camioneta&nbsp; a la Comisar\u00eda 2da, por razones de jurisdicci\u00f3n.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anoche, alrededor de las 20:30 personal de la Divisi\u00f3n Transito Urbano y Seguridad Vial de la termal inicio a diversos operativos cerrojos, cercando las rutas y caminos vecinales con la finalidad de detener a los presuntos autores y al recupero del rodado, que horas despu\u00e9s fue hallado. Es as\u00ed que &nbsp;en el puesto de control &hellip;<\/p>\n","protected":false},"author":2,"featured_media":7709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[42,8],"tags":[],"class_list":["post-7708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interior","category-policiales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/06\/990369b93b0f8e1f08310f73177c80a243277a5e.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7708"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7708\/revisions"}],"predecessor-version":[{"id":7710,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7708\/revisions\/7710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/7709"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}