{"id":75838,"date":"2023-05-03T21:24:21","date_gmt":"2023-05-04T00:24:21","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=75838"},"modified":"2023-05-03T21:25:31","modified_gmt":"2023-05-04T00:25:31","slug":"vuelven-a-subir-las-cuotas-de-las-prepagas","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/05\/03\/vuelven-a-subir-las-cuotas-de-las-prepagas\/","title":{"rendered":"Vuelven a subir las cuotas de las prepagas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Las cuotas de las prepagas aumentar\u00e1n en junio un 5,49% y a diferencia de los meses anteriores, esta vez ser\u00e1 igual para todos los afiliados sin importar su nivel de ingresos,<\/strong>&nbsp;ya que la suba calculada sobre la base de la variaci\u00f3n del \u00edndice de Remuneraci\u00f3n Imponible Promedio de los Trabajadores Estables (Ripte) es superior a ese nivel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera,<strong>&nbsp;el mes que viene quienes cobran hasta seis Salarios M\u00ednimos, Vitales y M\u00f3viles no deber\u00e1n completar el formulario para gozar de un tope en la suba de las prepagas ya que, esta vez, dicho tope est\u00e1 por encima del 5,49%.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En mayo las facturas de las prepagas est\u00e1n llegando con subas del 4,76%, pero que se reduce a 3,43% para quienes completaron una declaraci\u00f3n jurada<\/strong>, indicando que sus ingresos de marzo no superaron los 417 mil pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan los datos publicados por la Superintendencia de Servicios de Salud en su p\u00e1gina oficial, el \u00edndice de costos de salud, que es el par\u00e1metro que define los aumentos mensuales de precios, avanz\u00f3 un 5,49% en el per\u00edodo de referencia para los valores del sexto mes del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, el Ripte registr\u00f3 una variaci\u00f3n de 8,42%. De acuerdo con el mecanismo vigente desde febrero de este a\u00f1o, los usuarios que declaran tener ingresos no mayores a seis veces el salario m\u00ednimo pueden solicitar que la suba del precio de su plan de salud no supere el 90% de la variaci\u00f3n del \u00edndice Ripte. Pero, como en este caso ese 90% equivale a 7,58%, un porcentaje superior al del \u00edndice de costos del sector, de 5,49%, ser\u00e1 este \u00faltimo valor el que se usar\u00e1 para todos los contratos al definirse los precios de junio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las cuotas de las prepagas aumentar\u00e1n en junio un 5,49% y a diferencia de los meses anteriores, esta vez ser\u00e1 igual para todos los afiliados sin importar su nivel de ingresos,&nbsp;ya que la suba calculada sobre la base de la variaci\u00f3n del \u00edndice de Remuneraci\u00f3n Imponible Promedio de los Trabajadores Estables (Ripte) es superior a &hellip;<\/p>\n","protected":false},"author":2,"featured_media":75841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[639,46],"tags":[],"class_list":["post-75838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-salud"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/05\/Prepaga.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/75838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=75838"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/75838\/revisions"}],"predecessor-version":[{"id":75840,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/75838\/revisions\/75840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/75841"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=75838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=75838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=75838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}