{"id":75037,"date":"2023-04-17T11:49:54","date_gmt":"2023-04-17T14:49:54","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=75037"},"modified":"2023-04-17T11:49:56","modified_gmt":"2023-04-17T14:49:56","slug":"tesoro-en-la-valija-en-un-control-de-equipajes-descubrieron-monedas-de-oro","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/04\/17\/tesoro-en-la-valija-en-un-control-de-equipajes-descubrieron-monedas-de-oro\/","title":{"rendered":"Tesoro en la valija: en un control de equipajes descubrieron monedas de oro"},"content":{"rendered":"\n<p>El pasajero estaba listo para viajar a Chile, escala previa de su destino final, la ciudad de Barcelona, Espa\u00f1a. En su valija llevaba un tesoro oculto que no declar\u00f3:\u00a0<strong>13 monedas de oro de diferentes pa\u00edses y que pesaban 255 gramos<\/strong>. El hallazgo se produjo en las \u00faltimas horas en el aeropuerto internacional de Mendoza.<\/p>\n\n\n\n<p>El pasajero en cuesti\u00f3n es un ciudadano argentino que se dirig\u00eda a Santiago de Chile para hacer escala en un viaje que ten\u00eda como destino final Barcelona, en Espa\u00f1a.&nbsp;<strong>En el momento de la revisi\u00f3n del equipaje, el personal aduanero advirti\u00f3 numerosas piezas hechas de metales preciosos que el pasajero no hab\u00eda declarado\u201d,&nbsp;<\/strong>inform\u00f3 la Direcci\u00f3n General de Aduanas (DGA) en un comunicado de prensa.<\/p>\n\n\n\n<p>Las \u201cpiezas hechas de metales preciosos\u201d eran 13 monedas de oro de diferentes a\u00f1os y pa\u00edses y una\u00a0<strong>cadena enchapada en oro.<\/strong><\/p>\n\n\n\n<p><strong>\u201cLa Aduana se encuentra determinando el valor de la mercader\u00eda, pero el peso y composici\u00f3n de la misma apuntan a un monto en infracci\u00f3n de la\u00a0<\/strong>Resoluci\u00f3n General N\u00b0 2705\/2009 de la Administraci\u00f3n Federal de Ingresos P\u00fablicos (AFIP)<strong>, que establece que metales preciosos amonedados podr\u00e1n egresar del territorio nacional por la v\u00eda del r\u00e9gimen de equipaje\u00a0<\/strong>\u00fanicamente cuando su valor sea inferior a 10.000 d\u00f3lares\u201d, se explic\u00f3 en el citado comunicado.<\/p>\n\n\n\n<p>Tras el hallazgo, la Aduana labr\u00f3 un acta de infracci\u00f3n y dio aviso a la Justicia. El juez federal de Mendoza\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/politica\/elecciones-2023-un-juez-federal-de-mendoza-procesado-por-sobornos-volvera-a-controlar-los-comicios-nid27022023\/\">Walter Bento<\/a>\u00a0orden\u00f3 el secuestr\u00f3 de la mercader\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasajero estaba listo para viajar a Chile, escala previa de su destino final, la ciudad de Barcelona, Espa\u00f1a. En su valija llevaba un tesoro oculto que no declar\u00f3:\u00a013 monedas de oro de diferentes pa\u00edses y que pesaban 255 gramos. El hallazgo se produjo en las \u00faltimas horas en el aeropuerto internacional de Mendoza. El &hellip;<\/p>\n","protected":false},"author":2,"featured_media":75038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[639,8],"tags":[],"class_list":["post-75037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-policiales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/04\/la-aduana-descubrio-que-un-hombre-intentaba-salir-HH4CMYP2QBARJDOLCOEIFQFRMI.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/75037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=75037"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/75037\/revisions"}],"predecessor-version":[{"id":75039,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/75037\/revisions\/75039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/75038"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=75037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=75037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=75037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}