{"id":74575,"date":"2023-04-06T12:47:00","date_gmt":"2023-04-06T15:47:00","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=74575"},"modified":"2023-04-07T13:49:19","modified_gmt":"2023-04-07T16:49:19","slug":"martinez-inauguro-camino-a-la-redencion-obra-que-consta-de-14-murales-sobre-avenida-marconi","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2023\/04\/06\/martinez-inauguro-camino-a-la-redencion-obra-que-consta-de-14-murales-sobre-avenida-marconi\/","title":{"rendered":"Mart\u00ednez inaugur\u00f3 \u201cCamino a la redenci\u00f3n\u201d, obra que consta de 14 murales sobre avenida Marconi"},"content":{"rendered":"\n<p>En el marco del Jueves Santo, el intendente, Gustavo Mart\u00ednez, junto al arzobispo Ram\u00f3n Dus, la presidenta de la Legislatura Elida Cuesta y la comunidad cat\u00f3lica, particip\u00f3 del recorrido de las 14 estaciones de V\u00eda Crucis para inaugurar los murales que componen la obra \u00abCamino a la Redenci\u00f3n\u00bb, con la habilitaci\u00f3n de esas expresiones art\u00edsticas y religiosas presentes en la avenida Marconi, desde la colectora de ruta nacional 11 hasta inmediaciones de la avenida Hernandarias.<\/p>\n\n\n\n<p>Se trata de un recorrido de 2 kil\u00f3metros donde los resistencianos y turistas podr\u00e1n apreciar murales que recuerdan la Pasi\u00f3n, muerte y Resurrecci\u00f3n de Jesucristo. La iniciativa la realiz\u00f3 el Municipio de Resistencia junto a la comunidad de la Parroquia Sant\u00edsima Trinidad y la Fundaci\u00f3n Urunday, con la colaboraci\u00f3n de artistas locales y de otras provincias y pa\u00edses.<\/p>\n\n\n\n<p>\u201cEs muy importante para nosotros esta obra de la fe cat\u00f3lica, pero tambi\u00e9n es importante ratificar, a partir de las distintas expresiones culturales y religiosas, la identidad de Resistencia. Esto se expresa con 14 murales en toda la avenida Marconi y constituye un hito m\u00e1s de la identidad de Resistencia ligada al arte, a la cultura, a las esculturas, a los murales y al arte pl\u00e1stico, que es el gran potencial que tenemos\u201d, resalt\u00f3 Mart\u00ednez.<\/p>\n\n\n\n<p>A su vez, mencion\u00f3 que este corredor urbano y religioso es parte del plan \u201cAvenidas de mi ciudad\u201d y un reflejo de la revalorizaci\u00f3n de los espacios p\u00fablicos junto a la plazoleta del Estado de Israel y la Rep\u00fablica de Alemania que fue inaugurada en la avenida Lavalle.<\/p>\n\n\n\n<p>Adem\u00e1s, el Intendente invit\u00f3 a la comunidad a ser parte de las actividades previstas hasta el domingo de Pascua y expres\u00f3 sus expectativas respecto al turismo que se espera para disfrutar de las distintas propuestas que ofrece la Comuna. \u201cLos eventos art\u00edsticos, deportivos y culturales generan expansi\u00f3n en la econom\u00eda, no solamente en los emprendedores\u201d, dijo respecto al impacto positivo de esas actividades que ya son parte del sello de la gesti\u00f3n.<\/p>\n\n\n\n<p>La presidente de la Legislatura, \u00c9lida Cuesta, form\u00f3 parte de la ceremonia y valor\u00f3 el aporte del Municipio para generar este paseo muy especial para los cristianos, donde podr\u00e1n \u201cser reconfortados en la fe, en los sue\u00f1os y en los objetivos. Debemos tener esperanza de que vamos a salir adelante, porque estos son tiempos de reflexi\u00f3n sobre qu\u00e9 aporte hacemos desde el lugar que nos toca\u201d.<\/p>\n\n\n\n<p>Mientras que el padre Rafael Del Blanco, referente de la Parroquia Sant\u00edsima Trinidad, expres\u00f3 que la inauguraci\u00f3n de la obra es parte de \u201cun d\u00eda muy emotivo y muy importante para nosotros. Es un d\u00eda de mucha emoci\u00f3n y muchas bendiciones\u201d. A su vez valor\u00f3 el trabajo mancomunado entre las instituciones y los artistas, porque \u201cle dan un marco extraordinario a esta avenida que queremos sea reconocida como un paseo religioso\u201d.<\/p>\n\n\n\n<p><strong>LOS ARTISTAS<\/strong><\/p>\n\n\n\n<p>En una primera etapa participaron las artistas visuales, Gabriela Rubiolo, Natalia Almiron, Patricia Duran y Adriana Oplanich, integrantes del colectivo de artistas locales \u201cLola Mora\u201d quienes comenzaron a darle forma al proyecto.<\/p>\n\n\n\n<p>Durante la segunda etapa se cont\u00f3 con el apoyo del Departamento de Restauraci\u00f3n y Preservaci\u00f3n de Esculturas, Dependiente de la Direcci\u00f3n de Construcciones de la Direcci\u00f3n General de Obras por Adminiatraci\u00f3n de la Municipalidad de Resistencia y la Fundaci\u00f3n Urunday. As\u00ed bajo la Coordonacion General de Ceferino Ferreyra y el apoyo de Jorge Enrique, Ruben Ayala, Cristi\u00e1n Maciel, Hector Ledesma, la colaboraci\u00f3n de Gustavo Olivo y Leandro Ferreyra, sumado a los escultores Carlos Lopez y Gonzalo Colombo se procedi\u00f3 a finalizar el camino de la Redenci\u00f3n de Resistencia, que se convirti\u00f3 en un paseo religioso para toda la ciudad.<\/p>\n\n\n\n<p><strong>PR\u00d3XIMAS ACTIVIDADES<\/strong><\/p>\n\n\n\n<p>El viernes 7: a partir de las 18:30 horas, ser\u00e1 el V\u00eda Crucis, organizado por la comunidad de la parroquia Sant\u00edsima Trinidad, finalizando frente a la Casa Garrahan Chaco.<\/p>\n\n\n\n<p>El s\u00e1bado 8, a las 10 horas, se desarrollar\u00e1 el Rito de la Desolada en la capilla San Cayetano del barrio hom\u00f3nimo, dando lugar a una procesi\u00f3n acompa\u00f1ando a la Virgen Mar\u00eda hasta la sede de la Casa Garrahan Chaco.<\/p>\n\n\n\n<p>Esa misma jornada habr\u00e1 una serie de espect\u00e1culos art\u00edsticos se realizar\u00e1n en la pista de atletismo del Parque Intercultural \u201c2 de Febrero\u201d. Tambi\u00e9n habr\u00e1 stands de gastronom\u00eda local, los cerveceros del Litoral, foods trucks y el sendero de emprendedores. Comenzar\u00e1 a las 19:30 horas con la presencia de Djs Locales en vivo, m\u00fasica de los 80 y 90 y bandas en vivo con el legendario grupo \u201cDale Gas\u201d. Para las 22 horas cerrar\u00e1 la jornada la presentaci\u00f3n de la revista teatral chaque\u00f1a \u201cEl Virus no tiene corona\u201d.<\/p>\n\n\n\n<p>El domingo 9: a las 19 horas se efectuar\u00e1 la Misa Central de Pascuas en el Polideportivo de Villa Don Enrique, a cargo del padre Rafael del Blanco.<\/p>\n\n\n\n<p>Luego, el mismo lugar ser\u00e1 escenario del recital chamamecero a partir de las 20:30 horas con el show en vivo de Los De Imaguar\u00e9 y Mario y Fernando \u201cChingoli\u201d Bofill.<\/p>\n\n\n\n<p>Hasta el domingo 9 estar\u00e1 \u201cLagunas de tu ciudad\u201d, desde las 17 horas, evento al aire libre con m\u00fasica en vivo, bici botes, Food Trucks y juegos inflables para los m\u00e1s chiquitos. El mismo tendr\u00e1 lugar en las lagunas Francia, Seitor, Arg\u00fcello y Parque Intercultural \u201c2 de Febrero\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del Jueves Santo, el intendente, Gustavo Mart\u00ednez, junto al arzobispo Ram\u00f3n Dus, la presidenta de la Legislatura Elida Cuesta y la comunidad cat\u00f3lica, particip\u00f3 del recorrido de las 14 estaciones de V\u00eda Crucis para inaugurar los murales que componen la obra \u00abCamino a la Redenci\u00f3n\u00bb, con la habilitaci\u00f3n de esas expresiones art\u00edsticas &hellip;<\/p>\n","protected":false},"author":2,"featured_media":74576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[14,37],"tags":[],"class_list":["post-74575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/04\/MURALES-1-696x432-1.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/74575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=74575"}],"version-history":[{"count":2,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/74575\/revisions"}],"predecessor-version":[{"id":74578,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/74575\/revisions\/74578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/74576"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=74575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=74575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=74575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}