{"id":67142,"date":"2022-11-28T09:44:15","date_gmt":"2022-11-28T12:44:15","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=67142"},"modified":"2022-11-28T09:44:17","modified_gmt":"2022-11-28T12:44:17","slug":"brasil-sin-neymar-enfrenta-a-suiza-por-el-grupo-b","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2022\/11\/28\/brasil-sin-neymar-enfrenta-a-suiza-por-el-grupo-b\/","title":{"rendered":"Brasil, sin Neymar, enfrenta a Suiza por el Grupo B"},"content":{"rendered":"\n<p>Brasil, sin su m\u00e1xima figura Neymar, enfrentar\u00e1 hoy a Suiza en la segunda fecha del Grupo B, en donde el triunfo puede darles a cualquiera de los dos el pase a octavos de final de la Copa del Mundo en Qatar.<br>El partido se jugar\u00e1 desde las 13 (hora argentina) en el Estadio 974 en Ras Abu Aboud en Doha, con el arbitraje del salvadore\u00f1o Ivan Barton y transmisi\u00f3n de la TV P\u00fablica y DirectTV.<br>Brasil, que inici\u00f3 el torneo con un triunfo ante Serbia por 2-0 con dos tantos de Richarlison, no contar\u00e1 en los pr\u00f3ximos dos partidos ni con Neymar ni con Danilo, quienes sufrieron lesiones en sus tobillos derechos en la presentaci\u00f3n del equipo.<br>Suiza debut\u00f3 en Qatar 2022 con un triunfo por 1 a 0 ante Camer\u00fan gracias al gol en el segundo tiempo de Breel Embolo, la figura del encuentro disputado el jueves pasado, quien no festej\u00f3 su gol por haber nacido en el pa\u00eds africano.<br>Suiza y Brasil tambi\u00e9n se cruzaron en la fase de grupos del Mundial 2018 en Rusia, cuando igualaron 1-1.<\/p>\n\n\n\n<p><strong>Posibles formaciones<\/strong><\/p>\n\n\n\n<p>Suiza: Yann Sommer; Silvan Widmeer, Manuel Akanji, Nicol Elvedi y Ricardo Rodr\u00edguez; Remo Freuler, Granit Xhaka, Xherdan Shaqiri y Djibril Sow ; Ruben Vargas y Breel Embolo. DT: Murat Yakin.<\/p>\n\n\n\n<p>Brasil: Alisson; Militao, Thiago Silva, Marquinhos y Alex Sandro: Casemiro, Rodrygo. y Lucas Paquet\u00e1; Raphinha, Richarlison y Vinicius. DT: Tit\u00e9.<\/p>\n\n\n\n<p>Arbitro: Iv\u00e1n Cisneros (El Salvador)<\/p>\n\n\n\n<p>Estadio: 974, Ras Abu Aboud<\/p>\n\n\n\n<p>Hora inicio: 13 (hora argentina)<\/p>\n\n\n\n<p>TV: TV P\u00fablica y DirectTV.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brasil, sin su m\u00e1xima figura Neymar, enfrentar\u00e1 hoy a Suiza en la segunda fecha del Grupo B, en donde el triunfo puede darles a cualquiera de los dos el pase a octavos de final de la Copa del Mundo en Qatar.El partido se jugar\u00e1 desde las 13 (hora argentina) en el Estadio 974 en Ras &hellip;<\/p>\n","protected":false},"author":2,"featured_media":67143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15],"tags":[],"class_list":["post-67142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2022\/11\/ce5c3a80-393d-417b-b3c7-951c9481e232.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/67142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=67142"}],"version-history":[{"count":2,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/67142\/revisions"}],"predecessor-version":[{"id":67145,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/67142\/revisions\/67145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/67143"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=67142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=67142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=67142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}