{"id":58532,"date":"2022-06-24T09:39:44","date_gmt":"2022-06-24T12:39:44","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=58532"},"modified":"2022-06-24T09:39:47","modified_gmt":"2022-06-24T12:39:47","slug":"ucrania-pierde-mas-territorios-frente-a-un-devastador-avance-ruso-en-el-este","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2022\/06\/24\/ucrania-pierde-mas-territorios-frente-a-un-devastador-avance-ruso-en-el-este\/","title":{"rendered":"Ucrania pierde m\u00e1s territorios frente a un devastador avance ruso en el este"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Ej\u00e9rcito ruso conquist\u00f3 este jueves m\u00e1s territorio en el este de Ucrania, tras capturar dos poblados y un tramo de una ruta clave que le permite bloquear el abastecimiento de fuerzas ucranianas cada vez m\u00e1s rodeadas, informaron Ucrania y el Reino Unido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Defensa brit\u00e1nico dijo que unidades ucranianas se hab\u00edan retirado de la ciudad de Lisichansk, escenario de los combates m\u00e1s intensos, para evitar ser encerradas luego de que Rusia enviara refuerzos y bombardeara fuertemente la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estado mayor conjunto de las Fuerzas Armadas de Ucrania dijo que las fuerzas rusas tomaron control de los poblados de Loskutivka y Rai-Oleksandrivka, y que trataban de capturar el de Sirotine, a las afueras de la ciudad de Severodonetsk.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rusia controla la mayor parte de Severodonetsk, la capital administrativa de la provincia de Lugansk, luego de semanas de bombardeos a\u00e9reos y de artiller\u00eda y de duros combates calle por calle con el Ej\u00e9rcito ucraniano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ej\u00e9rcito ruso conquist\u00f3 este jueves m\u00e1s territorio en el este de Ucrania, tras capturar dos poblados y un tramo de una ruta clave que le permite bloquear el abastecimiento de fuerzas ucranianas cada vez m\u00e1s rodeadas, informaron Ucrania y el Reino Unido. El Ministerio de Defensa brit\u00e1nico dijo que unidades ucranianas se hab\u00edan retirado &hellip;<\/p>\n","protected":false},"author":2,"featured_media":58533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[],"class_list":["post-58532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2022\/06\/6290f24506fbd__375x250.webp","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/58532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=58532"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/58532\/revisions"}],"predecessor-version":[{"id":58534,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/58532\/revisions\/58534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/58533"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=58532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=58532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=58532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}