{"id":56399,"date":"2022-05-13T16:35:03","date_gmt":"2022-05-13T19:35:03","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=56399"},"modified":"2022-05-13T16:35:06","modified_gmt":"2022-05-13T19:35:06","slug":"frenaron-desmonte-ilegal-en-pampa-del-infierno","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2022\/05\/13\/frenaron-desmonte-ilegal-en-pampa-del-infierno\/","title":{"rendered":"Frenaron desmonte ilegal en Pampa del Infierno"},"content":{"rendered":"\n<p>Este viernes la Secci\u00f3n Rural Pampa del Infierno y Pampa Guanaco, irrumpieron en un campo sobre Ruta Provincial N\u00b05 y secuestraron una topadora que se encontraba derribando la masa forestal de nuestra provincia.<\/p>\n\n\n\n<p>Cerca de las 9, los rurales junto al personal de la Direcci\u00f3n de Bosques, realizaron un allanamiento en el Lote 98, a unos 11 kil\u00f3metros de la planta urbana de Pampa del Infierno, sobre la Ruta N\u00b05. Al momento de ingresar se encontraron con una casilla, cisternas con agua y combustibles, adem\u00e1s de otros elementos. Posteriormente escucharon los ruidos del motor de una m\u00e1quina que se encontraba campo adentro.<\/p>\n\n\n\n<p>Los polic\u00edas rastrearon el ruido y detectaron una topadora Caterpillar, derribando a su paso toda la masa boscosa. Inmediatamente frenaron el desmonte y demoraron al conductor de la m\u00e1quina de 36 a\u00f1os y constataron unas 30 hect\u00e1reas deforestadas.<\/p>\n\n\n\n<p>Horas m\u00e1s tarde se present\u00f3 el due\u00f1o de la maquinaria, un hombre de 43 a\u00f1os. La topadora fue secuestrada y el conductor junto al propietario de las maquinas, fueron notificados de su infracci\u00f3n al R\u00e9gimen Forestal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes la Secci\u00f3n Rural Pampa del Infierno y Pampa Guanaco, irrumpieron en un campo sobre Ruta Provincial N\u00b05 y secuestraron una topadora que se encontraba derribando la masa forestal de nuestra provincia. Cerca de las 9, los rurales junto al personal de la Direcci\u00f3n de Bosques, realizaron un allanamiento en el Lote 98, a &hellip;<\/p>\n","protected":false},"author":2,"featured_media":56400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,8],"tags":[],"class_list":["post-56399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-policiales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2022\/05\/627eaba38c15b147527225.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/56399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=56399"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/56399\/revisions"}],"predecessor-version":[{"id":56401,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/56399\/revisions\/56401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/56400"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=56399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=56399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=56399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}