{"id":5428,"date":"2020-04-20T21:09:52","date_gmt":"2020-04-21T00:09:52","guid":{"rendered":"http:\/\/portalmovil.com.ar\/?p=5428"},"modified":"2020-04-20T21:10:01","modified_gmt":"2020-04-21T00:10:01","slug":"plan-volver-a-casa-con-gran-despliegue-logistico-el-gobierno-gestiona-el-regreso-de-chaquenos-y-chaquenas","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/04\/20\/plan-volver-a-casa-con-gran-despliegue-logistico-el-gobierno-gestiona-el-regreso-de-chaquenos-y-chaquenas\/","title":{"rendered":"Plan volver a casa: con gran despliegue log\u00edstico el gobierno gestiona el regreso de chaque\u00f1os y chaque\u00f1as"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobierno provincial implementa el plan Volver a Casa, para ayudar a chaque\u00f1as y chaque\u00f1os que se encuentran en otras provincias a regresar a sus hogares para cumplir con la cuarentena obligatoria correspondiente. Hasta el momento 1700 personas pudieron volver a la provincia, en tanto ma\u00f1ana llegar\u00e1n otros dos micros desde Buenos Aires y en el mismo viaje, ciudadanos de esa ciudad, est\u00e1n retornando a sus domicilios. Adem\u00e1s, se gestionan pr\u00f3ximos viajes desde C\u00f3rdoba y Santa Fe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los operativos se enmarcan en las distintas habilitaciones y permisos que se definen de acuerdo a las medidas sanitarias dispuestas en el territorio nacional y las restricciones a la circulaci\u00f3n, por lo que requieren un gran trabajo de estrategia y log\u00edstica que demanda un tiempo correspondiente. \u201cEl gobierno se hace cargo del costo de los viajes, son totalmente gratuitos para las y los pasajeros\u201d, indic\u00f3 el subsecretario de Transporte de la provincia C\u00e9sar Frugoni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de un trabajo articulado desde el Ministerio del Interior, el Ministerio de Transporte y la Comisi\u00f3n Nacional Reguladora del Transporte (CNRT), as\u00ed como distintos organismos provinciales y municipales. \u201cSe realizaron acuerdos con el gobierno de Formosa, para organizar viajes en conjunto, tambi\u00e9n se articul\u00f3 con la Municipalidad de San Carlos de Bariloche y el Gobierno de R\u00edo Negro para que un grupo de 30 chaque\u00f1os y chaque\u00f1as regresen en esta semana\u201d, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frugoni destac\u00f3 el enorme esfuerzo del gobierno provincial para afrontar la situaci\u00f3n. Cada operativo requiere el trabajo y articulaci\u00f3n de diversas \u00e1reas del Estado provincial como los ministerios de Infraestructura, Log\u00edstica y Servicios P\u00fablicos, de Salud P\u00fablica, de Seguridad y Justicia, y de Gobierno y Trabajo. \u201cSeguimos recibiendo consultas de chaque\u00f1os que est\u00e1n dispersos en todo el territorio nacional y en el exterior, y se realiza el m\u00e1ximo esfuerzo para facilitar el regreso a casa, de acuerdo a todas las normativas nacionales y respetando estrictamente todas las normas sanitarias\u201d, advirti\u00f3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Riguroso protocolo sanitario<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El subsecretario de Gobierno Ra\u00fal Bittel destac\u00f3 el trabajo mancomunado entre las diversas \u00e1reas del Estado. \u201cCuando un grupo de chaque\u00f1os y chaque\u00f1as llega a la provincia, ingresan por el puente Chaco-Corrientes, \u00fanico punto de recepci\u00f3n y de ah\u00ed, veh\u00edculos del Estado los trasladan de manera segura a sus hogares para cumplir con el aislamiento\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Previamente, equipos sanitarios realizan los controles de salud pertinentes a cada pasajero, para conocer su estado de salud al momento del ingreso, y realizar el posterior seguimiento. \u201cSe les toma la temperatura y se les brindan los insumos necesarios \u2013 barbijo y alcohol en gel \u2013 para que puedan trasladarse en los veh\u00edculos a sus domicilios\u201d, explic\u00f3 .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas que tengan familiares fuera de la provincia con dificultad para volver, se pueden dirigir a la p\u00e1gina https:\/\/regresoacasa.argentina.gob.ar\/ adem\u00e1s de los relevamientos que se realizan tanto en Ezeiza como Retiro, para que se puedan instrumentar los mecanismos de regreso a la provincia y cuando llegan, se encuentren con el transporte que los llevar\u00e1 a sus domicilios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno provincial implementa el plan Volver a Casa, para ayudar a chaque\u00f1as y chaque\u00f1os que se encuentran en otras provincias a regresar a sus hogares para cumplir con la cuarentena obligatoria correspondiente. Hasta el momento 1700 personas pudieron volver a la provincia, en tanto ma\u00f1ana llegar\u00e1n otros dos micros desde Buenos Aires y en &hellip;<\/p>\n","protected":false},"author":2,"featured_media":5429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,3],"tags":[],"class_list":["post-5428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/04\/c91f146e-4a51-4421-8fba-74f6b2ebd95a.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5428"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5428\/revisions"}],"predecessor-version":[{"id":5430,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5428\/revisions\/5430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/5429"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}