{"id":53509,"date":"2022-03-28T19:46:24","date_gmt":"2022-03-28T22:46:24","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=53509"},"modified":"2022-03-28T19:46:27","modified_gmt":"2022-03-28T22:46:27","slug":"construiran-en-mendoza-el-primer-edificio-con-tuberias-de-vino","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2022\/03\/28\/construiran-en-mendoza-el-primer-edificio-con-tuberias-de-vino\/","title":{"rendered":"Construir\u00e1n en Mendoza el primer edificio con tuber\u00edas de vino"},"content":{"rendered":"\n<p>La ciudad de Mendoza es el centro de la enolog\u00eda en el pa\u00eds y es por ello que, en consecuencia, construir\u00e1n un edificio realizado con tuber\u00edas de vino, con el fin de fomentar la explotaci\u00f3n tur\u00edstica, a trav\u00e9s del alquiler de habitaciones.<\/p>\n\n\n\n<p>El proyecto que que en noviembre pasado recibi\u00f3 el Premio a la Innovaci\u00f3n de la Universidad Nacional de Cuyo, demandar\u00e1 una inversi\u00f3n total de U$S 1,5 millones y estar\u00e1 listo en 2025.&nbsp; El edificio estar\u00e1 ubicado a 200 metros del Parque General San Mart\u00edn, de Mendoza.<\/p>\n\n\n\n<p>\u201cBuscamos crear un concepto diferente, que saque al sector de la construcci\u00f3n de lo cl\u00e1sico. El edificio tendr\u00e1 ca\u00f1er\u00edas de agua fr\u00eda, agua caliente y vino. Es algo \u00fanico en el mundo. Adem\u00e1s, contar\u00e1 un vi\u00f1edo en la terraza y una cava en la cochera\u201d, detall\u00f3 Mat\u00edas Merino, presidente de Pir Real Estate, empresa que llevar\u00e1 adelante la construcci\u00f3n del edificio.<\/p>\n\n\n\n<p>La tuber\u00eda de vino ser\u00e1 de acero inoxidable y tendr\u00e1 un sistema independiente al del agua.&nbsp;<strong>\u201cEl vino llegar\u00e1 a cada habitaci\u00f3n por bombeo y se abastecer\u00e1 de un tanque especialmente adaptado para conservar el vino de la mejora manera\u201d,<\/strong>&nbsp;coment\u00f3 el empresario.<\/p>\n\n\n\n<p>\u201cEl varietal se definir\u00e1 de acuerdo a la demanda del mercado. No tendremos siempre el mismo producto\u201d, aclar\u00f3.<\/p>\n\n\n\n<p>En los amenities est\u00e1 incluida la cava del subsuelo y el vi\u00f1edo de la terraza. \u201cSon espacios pensados para que los turistas se tomen fotos. Buscamos tener espacios \u2018instagrameables\u2019. Hoy en los hoteles se usan carteles con el nombre de ciudades justamente con ese fin\u201d, agreg\u00f3 el empresario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad de Mendoza es el centro de la enolog\u00eda en el pa\u00eds y es por ello que, en consecuencia, construir\u00e1n un edificio realizado con tuber\u00edas de vino, con el fin de fomentar la explotaci\u00f3n tur\u00edstica, a trav\u00e9s del alquiler de habitaciones. El proyecto que que en noviembre pasado recibi\u00f3 el Premio a la Innovaci\u00f3n &hellip;<\/p>\n","protected":false},"author":2,"featured_media":53510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,639],"tags":[],"class_list":["post-53509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-argentina"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2022\/03\/f40e4a92-459a-4937-84ed-2ba1cd26ad2c.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53509"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53509\/revisions"}],"predecessor-version":[{"id":53511,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53509\/revisions\/53511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/53510"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}