{"id":52325,"date":"2022-03-09T14:46:53","date_gmt":"2022-03-09T17:46:53","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=52325"},"modified":"2022-03-09T14:46:55","modified_gmt":"2022-03-09T17:46:55","slug":"capitanich-busca-traer-inversiones-desde-dubai-para-chaco","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2022\/03\/09\/capitanich-busca-traer-inversiones-desde-dubai-para-chaco\/","title":{"rendered":"Capitanich busca traer inversiones desde Dubai para Chaco"},"content":{"rendered":"\n<p>El gobernador Jorge Capitanich puso en marcha este mi\u00e9rcoles una agenda de negocios en los Emiratos \u00c1rabes Unidos, exponiendo las oportunidades de abrir nuevos mercados con el desarrollo de 13 proyectos ejecutivos por un monto de 708 millones de d\u00f3lares de inversi\u00f3n, que a su vez pueden generar cerca de 10 mil empleos directos e indirectos. \u201cAqu\u00ed hay liquidez y excedente de fondos, compran lo que podemos producir y es una gran posibilidad para atraer inversiones y expandir el desarrollo de la industria, el comercio y la producci\u00f3n\u201d, asegur\u00f3.<\/p>\n\n\n\n<p>La ronda inici\u00f3 en Dubai Airport Free Zone (DAFZA) -zona franca de comercio- junto a una nutrida comitiva argentina compuesta por el gobernador de Santiago del Estero y presidente del Consejo del Norte Grande, Gerardo Zamora; el secretario general del Consejo Federal de Inversiones (CFI), Ignacio Lamothe; y el embajador argentino, Jorge Molina Arambarri, adem\u00e1s de empresarios de la provincia e inversionistas del norte argentino.<\/p>\n\n\n\n<p>Este aeropuerto, con un tr\u00e1nsito de cerca de 89 millones de pasajeros, constituye un importante centro de comercializaci\u00f3n. \u201cEsta zona franca es extraordinaria, significa una oportunidad \u00fanica para el desarrollo de inversiones porque est\u00e1n radicadas cerca de dos mil empresas con un gran nivel de integraci\u00f3n que implican un importante soporte para la comercializaci\u00f3n de nuestros bienes\u201d, indic\u00f3.<\/p>\n\n\n\n<p>El mandatario chaque\u00f1o realiz\u00f3 una extensa exposici\u00f3n sobre las potencialidades del norte grande argentino, que cuenta con casi 850 mil kil\u00f3metros cuadrados de extensi\u00f3n y constituye el 21% de la poblaci\u00f3n total del pa\u00eds con cerca de 10 millones de habitantes, remarcando la importancia de que las provincias adquieran una visi\u00f3n estrat\u00e9gica para generar m\u00e1s relaciones comerciales con este hub log\u00edstico. \u201cTenemos en nuestras respectivas provincias todo para ofrecer. Este es un mundo que demanda cada d\u00eda m\u00e1s alimentos y bienes que nosotros producimos\u201d, dijo.<\/p>\n\n\n\n<p>\u201cLa zona franca es una plataforma de comercio que tiene Dubai con incentivos extraordinarios y simplificaci\u00f3n de tr\u00e1mites con el objeto de tener una base exportadora; gran parte de los productos que aqu\u00ed se comercializan se compran y se redistribuyen principalmente en los mercados asi\u00e1ticos. Lo que hemos planteado con ellos es la posibilidad de que el norte grande use las instalaciones de la zona franca\u201d, se\u00f1al\u00f3 Capitanich.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Inter\u00e9s en el Chaco<\/strong><\/h2>\n\n\n\n<p>Por la tarde, el gobernador se reuni\u00f3 en el hotel Fairmont con representantes de distintos fondos de inversi\u00f3n, uno de ellos y el m\u00e1s importante, Emirates Focus Group, que ya visit\u00f3 la provincia del Chaco previamente bajo la representaci\u00f3n de Tahnoon Nimer. \u201cEstar aqu\u00ed y compartir con los fondos es muy importante, y lo m\u00e1s trascendente es el hecho de que han mostrado inter\u00e9s en definir r\u00e1pido posibilidades de inversi\u00f3n\u201d, cont\u00f3, acompa\u00f1ado adem\u00e1s por el ministro de Industria, Producci\u00f3n y Empleo, Sebasti\u00e1n Lifton, y la subsecretaria de Comercio Exterior y Defensa de la Competencia, Ludmila Voloj.<\/p>\n\n\n\n<p>Posteriormente el gobernador se reuni\u00f3 con Mohamed Shafiq el CEO de Jampur Group y dem\u00e1s autoridades. Se trata de una compa\u00f1\u00eda de servicios log\u00edsticos que tiene su sede en Dubai pero que opera en pa\u00edses de \u00c1frica, Europa y Asia, ofreciendo soluciones de env\u00edo, energ\u00eda, miner\u00eda, equipos y comercio.<\/p>\n\n\n\n<p>Con ellos tambi\u00e9n hizo hincapi\u00e9 en las bondades del Norte grande. \u201cTenemos diferentes tipos de producci\u00f3n, minerales estrat\u00e9gicos, miel, productos textiles, soja, ma\u00edz, girasol y productos alimenticios de excelente calidad. Las provincias del norte argentino son un importante espacio para el desarrollo de nuevas inversiones en el pa\u00eds y requieren una especial atenci\u00f3n para la expansi\u00f3n de la actividad econ\u00f3mica\u201d, dijo el mandatario, acompa\u00f1ado adem\u00e1s por el empresario Rodrigo Ojeda, presidente de la textil Zutt Protect.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Empresas con oportunidad de exportaci\u00f3n<\/strong><\/h2>\n\n\n\n<p>De la reuni\u00f3n con Emirates Focus Group particip\u00f3 Fabi\u00e1n Ardeti, CEO del grupo Insuga radicado en Puerto Tirol, que present\u00f3 dos de los productos esenciales que ofrece la empresa: harina de carne y hueso y sebo vacuno industrial, dirigidos a f\u00e1bricas de alimentos balanceados y a la elaboraci\u00f3n de productos con alto valor agregado como jabones de distintas calidades, grasas y margarinas refinadas, respectivamente.<\/p>\n\n\n\n<p>\u201cEs la primera vez que venimos a Emiratos \u00c1rabes, a pesar de que somos una empresa exportadora nunca hemos incursionado en esta zona del mundo y lo que nos interesa es justamente la posibilidad de adoptar a Dubai y sus puertos como un hub de distribuci\u00f3n para poder llegar a las zonas lim\u00edtrofes y los pa\u00edses del norte de \u00c1frica\u201d, apuntal\u00f3 el empresario.<\/p>\n\n\n\n<p>Tambi\u00e9n estuvo Lucas Andersen, gerente de Argenmieles, empresa productora de miel que forma parte del grupo San Blas; exporta a m\u00e1s de 16 destinos en el mundo y ya tuvo experiencia de exportaci\u00f3n a los Emiratos \u00c1rabes. Chaco es la primera provincia productora de miel org\u00e1nica certificada de la Argentina, tercer pa\u00eds productor de miel en el mundo con una participaci\u00f3n muy importante en el mercado que alcanza el 25% en el continente americano, 70% en sudam\u00e9rica y 6% a nivel mundial.<\/p>\n\n\n\n<p>\u201cVengo en colaboraci\u00f3n con productores de la provincia y de la zona de El Impenetrable, un \u00e1rea de m\u00e1s de 3 millones de hect\u00e1reas de bosques nativos en la que desde hace a\u00f1os venimos desarrollando un proyecto de miel org\u00e1nica de alt\u00edsima calidad. Solamente se explota el 20% de esa superficie as\u00ed que tiene una potencialidad enorme para seguir desarroll\u00e1ndose\u201d, les dijo Andersen a los empresarios \u00e1rabes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Log\u00edstica para integrar al Norte&nbsp;<\/strong><\/h2>\n\n\n\n<p>El ministro Sebasti\u00e1n Lifton puso especial \u00e9nfasis en las inversiones que necesita atraer la provincia para acelerar la integraci\u00f3n del transporte log\u00edstico, principalmente para el funcionamiento pleno del puerto Barranqueras y para la finalizaci\u00f3n de las obras del puerto Las Palmas.<\/p>\n\n\n\n<p>\u201cLa provincia tiene un puerto en funcionamiento (Barranqueras) y tiene un segundo puerto en proceso (Las Palmas) con un proyecto de generaci\u00f3n de zona franca en carpeta. A su vez, por tener hacia el este la hidrov\u00eda Paran\u00e1-Paraguay, necesitamos trabajar un puerto seco integrado a este proceso ya sea en el centro o en el sudoeste de la provincia. Es decir, tenemos un conglomerado log\u00edstico muy importante que requiere un proceso acelerado de inversiones\u201d, indic\u00f3 Lifton.<\/p>\n\n\n\n<p>\u201cEs clave la integraci\u00f3n que puede tener el norte argentino y los mercados que puedan surgir con la visita comercial de nuestras empresas aqu\u00ed en Emiratos y hacia el resto de la regi\u00f3n, y para ello es necesario tratar la log\u00edstica integrada, no s\u00f3lo en nuestra provincia sino en todo el norte del pa\u00eds\u201d, sostuvo el ministro de Producci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Jorge Capitanich puso en marcha este mi\u00e9rcoles una agenda de negocios en los Emiratos \u00c1rabes Unidos, exponiendo las oportunidades de abrir nuevos mercados con el desarrollo de 13 proyectos ejecutivos por un monto de 708 millones de d\u00f3lares de inversi\u00f3n, que a su vez pueden generar cerca de 10 mil empleos directos e &hellip;<\/p>\n","protected":false},"author":2,"featured_media":52326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,14,12],"tags":[],"class_list":["post-52325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-politica","category-ultimo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2022\/03\/378308f6ecd978168ccd52c7b1a3ca77.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=52325"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52325\/revisions"}],"predecessor-version":[{"id":52327,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52325\/revisions\/52327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/52326"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=52325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=52325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=52325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}