{"id":47351,"date":"2021-12-28T09:28:01","date_gmt":"2021-12-28T12:28:01","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=47351"},"modified":"2021-12-28T09:28:03","modified_gmt":"2021-12-28T12:28:03","slug":"prorrogan-ampliacion-de-competencias-en-juzgados-de-ninez-adolescencia-y-familia-de-resistencia","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/12\/28\/prorrogan-ampliacion-de-competencias-en-juzgados-de-ninez-adolescencia-y-familia-de-resistencia\/","title":{"rendered":"Prorrogan ampliaci\u00f3n de competencias en juzgados de Ni\u00f1ez, Adolescencia y Familia de Resistencia"},"content":{"rendered":"\n<p>Ser\u00e1 por un a\u00f1o, a partir del 1 de marzo de 2022. As\u00ed lo estableci\u00f3 el Superior Tribunal de Justicia del Chaco mediante la resoluci\u00f3n 1150\/21 con el objetivo de \u201clograr la equidad en la redistribuci\u00f3n de las tareas diarias, a fin de evitar el colapso de cierto sector, en referencia a otro del mismo fuero y circunscripci\u00f3n\u201d; puesto que a\u00fan subsisten \u201clas razones que dieron origen a la reestructuraci\u00f3n del fuero\u201d.<\/p>\n\n\n\n<p>Con el objetivo de \u201clograr la equidad en la redistribuci\u00f3n de las tareas diarias, a fin de evitar el colapso de cierto sector, en referencia a otro del mismo fuero y circunscripci\u00f3n\u201d; puesto que a\u00fan subsisten \u201clas razones que dieron origen a la reestructuraci\u00f3n del fuero\u201d, el Superior Tribunal de Justicia del Chaco resolvi\u00f3 prorrogar por un a\u00f1o la ampliaci\u00f3n de competencias de los Juzgados de Ni\u00f1ez, Adolescencia y Familia a partir del pr\u00f3ximo 1 de marzo de 2022.<\/p>\n\n\n\n<p>Adem\u00e1s, la ampliaci\u00f3n de la competencia establecida en la resoluci\u00f3n N\u00b0 80\/2020 quedar\u00e1 distribuida de la siguiente forma:<\/p>\n\n\n\n<p>\u00b7 Juzgados NAyF N\u00b0 1, 2, 5 y 6: entender\u00e1n en las causas enumeradas en el art\u00edculo 3 de la ley 2950-M, incisos 1 a 9, 11 y 13 a 18, inclusive.<\/p>\n\n\n\n<p>\u00b7 Juzgados NAyF N\u00b0 3 y 4: son competentes adem\u00e1s de las causas que se tramiten por las normas del proceso penal, conforme ley 2951-N y las dispuestas por la resoluci\u00f3n N\u00b0 80\/2020, en las contenidas en el inciso 10 del art\u00edculo 3 de la ley citada.<\/p>\n\n\n\n<p>Por otra parte, la Sala Civil, Comercial y Laboral deber\u00e1 redactar un proyecto de ley que propicie una modificaci\u00f3n integral de los juzgados de Ni\u00f1ez, Adolescencia y Familia de la primera circunscripci\u00f3n judicial y su competencia actual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 por un a\u00f1o, a partir del 1 de marzo de 2022. As\u00ed lo estableci\u00f3 el Superior Tribunal de Justicia del Chaco mediante la resoluci\u00f3n 1150\/21 con el objetivo de \u201clograr la equidad en la redistribuci\u00f3n de las tareas diarias, a fin de evitar el colapso de cierto sector, en referencia a otro del mismo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":47352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50,37],"tags":[],"class_list":["post-47351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-judiciales","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/12\/fuero-de-familia.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=47351"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47351\/revisions"}],"predecessor-version":[{"id":47353,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47351\/revisions\/47353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/47352"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=47351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=47351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=47351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}