{"id":47340,"date":"2021-12-28T09:09:25","date_gmt":"2021-12-28T12:09:25","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=47340"},"modified":"2021-12-28T09:09:29","modified_gmt":"2021-12-28T12:09:29","slug":"habilitaron-el-adelanto-chaco-24-del-nbch","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/12\/28\/habilitaron-el-adelanto-chaco-24-del-nbch\/","title":{"rendered":"Habilitaron el Adelanto Chaco 24 del NBCh"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El servicio de Adelanto Chaco 24 de Nuevo Banco del Chaco ya est\u00e1 disponible para anticipar compras con tarjeta de d\u00e9bito para activos y pasivos provinciales, empleados de empresas del Estado, Ecom, Sameep y Secheep. Por su parte, las empresas privadas que tienen convenio de pago de haberes pueden solicitarlo para sus empleados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adelanto Chaco 24 permite realizar compras en cualquier comercio con tarjeta de d\u00e9bito Chaco 24 sin pagar intereses y sin disponer de saldo en cuenta. Este servicio se encuentra disponible hasta la acreditaci\u00f3n de haberes, luego se descuenta \u00fanicamente el importe utilizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este servicio de Nuevo Banco del Chaco se habilita de forma autom\u00e1tica, sin necesidad de realizar ning\u00fan tr\u00e1mite o gesti\u00f3n. Una vez recibido el pago de haberes, el monto utilizado se debita autom\u00e1ticamente. Asimismo, el uso del servicio no tiene costos adicionales, comisiones o intereses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adelanto Chaco 24 permite realizar compras de todo tipo, en comercios de distintos rubros como supermercados, almacenes, estaciones de servicios, restaurantes, farmacias y tiendas de indumentaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El servicio de Adelanto Chaco 24 de Nuevo Banco del Chaco ya est\u00e1 disponible para anticipar compras con tarjeta de d\u00e9bito para activos y pasivos provinciales, empleados de empresas del Estado, Ecom, Sameep y Secheep. Por su parte, las empresas privadas que tienen convenio de pago de haberes pueden solicitarlo para sus empleados. Adelanto Chaco &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,175],"tags":[],"class_list":["post-47340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/06\/nbch_tarjeta_debito_1_100258_100258.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=47340"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47340\/revisions"}],"predecessor-version":[{"id":47341,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47340\/revisions\/47341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/8384"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=47340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=47340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=47340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}