{"id":39160,"date":"2021-09-05T19:51:02","date_gmt":"2021-09-05T22:51:02","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=39160"},"modified":"2021-09-05T19:51:09","modified_gmt":"2021-09-05T22:51:09","slug":"capitanich-queremos-el-voto-para-seguir-transformando-la-provincia-con-hechos-y-no-palabras","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/09\/05\/capitanich-queremos-el-voto-para-seguir-transformando-la-provincia-con-hechos-y-no-palabras\/","title":{"rendered":"Capitanich: \u201cQueremos el voto para seguir transformando la provincia con hechos y no palabras\u201d"},"content":{"rendered":"\n<p>El gobernador Jorge Capitanich encabez\u00f3 dos nuevos actos de campa\u00f1a en las localidades de Pampa del Indio y Presidencia Roca, donde llev\u00f3 las propuestas del Frente de Todos Chaco y su lista 501 R &#8211; 17 de Octubre para las pr\u00f3ximas elecciones. \u201cQueremos el voto del pueblo chaque\u00f1o para seguir transformando la provincia con hechos y no palabras\u201d, remarc\u00f3 el mandatario.<\/p>\n\n\n\n<p>El primero de los actos tuvo lugar en Pampa del Indio, donde junto al intendente Gustavo Karasiuk, el gobernador se\u00f1al\u00f3: \u201cQueremos acompa\u00f1ar al presidente con un federalismo aut\u00e9ntico que ya no acepta palabras, y solamente acepta hechos. Queremos la reivindicaci\u00f3n hist\u00f3rica que se traduzca en obras, pol\u00edticas equitativas y desarrollo para todos los chaque\u00f1os y chaque\u00f1as\u201d.&nbsp;<\/p>\n\n\n\n<p>En el lugar, Capitanich hizo un repaso de las obras logradas por su gesti\u00f3n actual y las anteriores al frente de la provincia: \u201cel a\u00f1o pasado vine a inaugurar la escuela 969, ahora la 968, inauguramos el hospital, hicimos pavimento urbano, la repavimentaci\u00f3n de la ruta 4 y su extensi\u00f3n, la ruta 3 que conecta con Villa R\u00edo Bermejito, unimos con pavimento el Pueblo viejo, construimos el CIC y los centros de salud de la zona, la remodelaci\u00f3n de la escuela Santa Rita, la regulaci\u00f3n del R\u00edo Guaycur\u00fa, m\u00e1s electrificaci\u00f3n rural, viviendas, y redes de agua potable\u201d, enumer\u00f3.&nbsp;<\/p>\n\n\n\n<p>En Presidencia Roca, el gobernador inici\u00f3 su discurso valorando a las mujeres ind\u00edgenas en su d\u00eda, y comparti\u00f3 un discurso en el que hizo un repaso por las pol\u00edticas hist\u00f3ricas del peronismo para el Chaco. \u201cEstamos recuperando la impronta federal. Hoy empu\u00f1amos las banderas del federalismo y &nbsp;honramos la memoria de Belgrano, San Mart\u00edn, G\u00fcemes, Per\u00f3n, Evita, N\u00e9stor y Cristina para fortalecer la conducci\u00f3n pol\u00edtica de Alberto Fern\u00e1ndez y hacer lo que nos falta\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, Capitanich repas\u00f3 algunas de las principales obras de su gesti\u00f3n en la localidad. \u201cAqu\u00ed estamos con un plan de pavimento urbano, la operatoria 613 que permiti\u00f3 equipar al municipio, con las obras para alcanzar 8069 conexiones domiciliarias de agua potable mediante el acueducto de las siete localidades. Y logramos hacer redes de energ\u00eda el\u00e9ctrica, el hospital, rutas, y tantas obras m\u00e1s que son visibiles, palpables y que cambian la calidad de vida de las comunidades\u201d.<\/p>\n\n\n\n<p>Participaron del acto los precandidatos a diputados nacionales Juan Manuel Pedrini y Silvana Cabrera, junto a las precandidatas y precandidatos a diputados provinciales Mariela Quir\u00f3s, Juan Jos\u00e9 Bergia, Luciana Delgado y Gustavo D\u2019Alessandro. Adem\u00e1s estuvo presente el diputado nacional Aldo Leiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Jorge Capitanich encabez\u00f3 dos nuevos actos de campa\u00f1a en las localidades de Pampa del Indio y Presidencia Roca, donde llev\u00f3 las propuestas del Frente de Todos Chaco y su lista 501 R &#8211; 17 de Octubre para las pr\u00f3ximas elecciones. \u201cQueremos el voto del pueblo chaque\u00f1o para seguir transformando la provincia con hechos &hellip;<\/p>\n","protected":false},"author":2,"featured_media":39161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,14],"tags":[],"class_list":["post-39160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/09\/61352a0c41cfe404284647.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/39160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=39160"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/39160\/revisions"}],"predecessor-version":[{"id":39162,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/39160\/revisions\/39162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/39161"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=39160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=39160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=39160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}