{"id":38826,"date":"2021-09-01T20:26:48","date_gmt":"2021-09-01T23:26:48","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=38826"},"modified":"2021-09-01T20:29:16","modified_gmt":"2021-09-01T23:29:16","slug":"sancionaran-a-las-empresas-de-colectivos-que-no-cumplan-con-la-frecuencia-establecida-en-resistencia","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/09\/01\/sancionaran-a-las-empresas-de-colectivos-que-no-cumplan-con-la-frecuencia-establecida-en-resistencia\/","title":{"rendered":"Sancionar\u00e1n a las empresas de colectivos que no cumplan con la frecuencia establecida en Resistencia"},"content":{"rendered":"\n<p>El subsecretario de Transporte, Luis Cabrera, asegur\u00f3 que mediante el monitoreo del transporte p\u00fablico<strong>&nbsp;se detect\u00f3 la excesiva espera en la frecuencia y comunic\u00f3 que las empresas con irregularidades no justificadas en la frecuencia, ser\u00e1n sancionadas y se dictar\u00e1n las intimidaciones correspondientes<\/strong>. El objetivo es continuar priorizando al usuario, a cada ciudadano, su bienestar y el valor de su tiempo.<\/p>\n\n\n\n<p>Cabrera explic\u00f3 que \u00abla Subsecretar\u00eda de Transporte se dispone a librar las intimidaciones correspondientes bajo apercibimiento de dictar caducidad de los contratos vigentes a las empresas con irregularidades\u00bb y afirm\u00f3 que&nbsp;<strong>el monitoreo del transporte es una herramienta de control y diagn\u00f3stico \u00abpermanente\u00bb para la determinaci\u00f3n de medidas a corto y mediano plazo<\/strong>&nbsp;en el marco de la planificaci\u00f3n municipal.<\/p>\n\n\n\n<p>Sostuvo que las esperas excesivas en la frecuencia son multicausales y que&nbsp;<strong>se han sacado ocho unidades de circulaci\u00f3n por el estado de los veh\u00edculos<\/strong>. Tambi\u00e9n se constat\u00f3 que \u00abalgunas empresas no est\u00e1n cumpliendo con los ramales\u00bb y mencion\u00f3 a las l\u00edneas 2,4, 5, 8 y 12.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"634\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/09\/whatsapp_image_2021-09-01_at_11.41.12-1024x634.jpeg\" alt=\"\" class=\"wp-image-38827\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/09\/whatsapp_image_2021-09-01_at_11.41.12-1024x634.jpeg 1024w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/09\/whatsapp_image_2021-09-01_at_11.41.12-300x186.jpeg 300w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/09\/whatsapp_image_2021-09-01_at_11.41.12-768x476.jpeg 768w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/09\/whatsapp_image_2021-09-01_at_11.41.12.jpeg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Por otro lado, invit\u00f3 a la reflexi\u00f3n y solidaridad de algunos movimientos sociales que se trasladan por el corredor del transporte p\u00fablico produciendo demoras en el contexto de su reclamo: \u00ab<strong>El objetivo de algunos sectores es molestar a la ciudadan\u00eda generando demoras en la espera del colectivo de una hora<\/strong>\u00ab.&nbsp;<\/p>\n\n\n\n<p>Finalmente, reiter\u00f3 su solicitud de colaboraci\u00f3n: \u00abCon mucha humildad, entendemos el reclamo social, pero no puede significar que represente un reclamo al ciudadano de a pie, la queja es hacia los eslabones del Estado que correspondan y no es sano para ninguna sociedad tomar de reh\u00e9n al usuario\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El subsecretario de Transporte, Luis Cabrera, asegur\u00f3 que mediante el monitoreo del transporte p\u00fablico se detect\u00f3 la excesiva espera en la frecuencia y comunic\u00f3 que las empresas con irregularidades no justificadas en la frecuencia, ser\u00e1n sancionadas y se dictar\u00e1n las intimidaciones correspondientes. El objetivo es continuar priorizando al usuario, a cada ciudadano, su bienestar y el valor de su tiempo.<\/p>\n","protected":false},"author":2,"featured_media":38833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[37,3],"tags":[],"class_list":["post-38826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resistencia","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/09\/22889w720.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=38826"}],"version-history":[{"count":2,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38826\/revisions"}],"predecessor-version":[{"id":38831,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38826\/revisions\/38831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/38833"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=38826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=38826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=38826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}