{"id":38435,"date":"2021-08-29T09:59:46","date_gmt":"2021-08-29T12:59:46","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=38435"},"modified":"2021-08-29T09:59:49","modified_gmt":"2021-08-29T12:59:49","slug":"corrientes-elige-gobernador-intendentes-y-legisladores","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/08\/29\/corrientes-elige-gobernador-intendentes-y-legisladores\/","title":{"rendered":"Corrientes elige gobernador, intendentes y legisladores"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los comicios provinciales en\u00a0Corrientes\u00a0para elegir gobernador y vice, legisladores, intendentes y concejales se iniciaron hoy con demoras en gran parte de los establecimientos educativos dispuestos para sufragar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se presume que la tardanza se debe al incremento de escuelas y mesas para los electores y a las medidas sanitarias adoptadas con el fin de evitar la concentraci\u00f3n por la pandemia de coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, el ministro de Seguridad de la provincia, Juan Jos\u00e9 L\u00f3pez Desimoni, afirm\u00f3 hoy que el acto el electoral se inici\u00f3 \u201ccon total normalidad\u201d tanto en la Capital como en el interior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada electoral se desarrolla en Corrientes en un d\u00eda soleado en todo el territorio provincial, donde se espera una temperatura m\u00e1xima de 27 grados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s de 860 mil correntinos est\u00e1n habilitados para votar en las\u00a0elecciones\u00a0provinciales para elegir gobernador, intendentes y legisladores, en una competencia polarizada entre la alianza gobernante ECO+Vamos Corrientes y el Frente Corrientes de Todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La disputa por la gobernaci\u00f3n enfrenta a la f\u00f3rmula Gustavo Vald\u00e9s-Pedro Braillard Poccard, de la alianza liderada por la Uni\u00f3n C\u00edvica Radical, y a la dupla peronista Fabi\u00e1n R\u00edos-Mart\u00edn Barrionuevo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Corrientes elige gobernador y vice, cinco senadores y 15 diputados provinciales, as\u00ed como intendentes y concejales en 57 municipios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son en total 868.288 los electores habilitados para emitir el sufragio en toda la provincia en 853 escuelas en las que est\u00e1n distribuidas 2.566 mesas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los comicios provinciales en\u00a0Corrientes\u00a0para elegir gobernador y vice, legisladores, intendentes y concejales se iniciaron hoy con demoras en gran parte de los establecimientos educativos dispuestos para sufragar. Se presume que la tardanza se debe al incremento de escuelas y mesas para los electores y a las medidas sanitarias adoptadas con el fin de evitar la &hellip;<\/p>\n","protected":false},"author":2,"featured_media":38436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[639,14],"tags":[],"class_list":["post-38435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-politica"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/08\/corrientes-.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=38435"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38435\/revisions"}],"predecessor-version":[{"id":38437,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38435\/revisions\/38437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/38436"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=38435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=38435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=38435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}