{"id":35325,"date":"2021-08-02T09:42:11","date_gmt":"2021-08-02T12:42:11","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=35325"},"modified":"2021-08-02T09:42:14","modified_gmt":"2021-08-02T12:42:14","slug":"barcelona-no-pierde-las-esperanzas-de-acuerdo-con-messi","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/08\/02\/barcelona-no-pierde-las-esperanzas-de-acuerdo-con-messi\/","title":{"rendered":"Barcelona no pierde las esperanzas de acuerdo con Messi"},"content":{"rendered":"\n<p>El club Barcelona espera llegar a un acuerdo con Lionel Messi durante los pr\u00f3ximos d\u00edas y contar con el astro argentino a partir del pr\u00f3ximo 8 de agosto, seg\u00fan se\u00f1ala hoy la prensa espa\u00f1ola.<\/p>\n\n\n\n<p>El presidente del club catal\u00e1n, Joan Laporta, reiter\u00f3 en las \u00faltimas horas que las tratativas para el nuevo contrato con Messi \u00abest\u00e1n bien encaminadas\u00bb, destac\u00f3 el diario Mundo Deportivo.<\/p>\n\n\n\n<p>\u00abTodo va bien seg\u00fan lo previsto. Todo progresa adecuadamente, todo va bien\u00bb, reiter\u00f3 el presidente azulgrana.<\/p>\n\n\n\n<p>Desde el entorno de Messi y tambi\u00e9n desde el Barcelona descartan que el futbolista se reintegre a los entrenamientos con el plantel que dirige el neerland\u00e9s Ronald Koeman hasta tanto no se firme el nuevo contrato, que seg\u00fan trascendi\u00f3 ser\u00eda hasta 2026 y en el que Messi habr\u00eda aceptado una rebaja salarial de hasta un 50 por ciento.<\/p>\n\n\n\n<p>En el Barcelona \u00abconf\u00edan\u00bb en poder tener a Messi con el nuevo contrato antes de que se juegue el tradicional Trofeo Joan Gamper, del domingo 8 de agosto.<\/p>\n\n\n\n<p>El club \u00abcul\u00e9\u00bb trabaja en la adecuaci\u00f3n salarial de los \u00abpesos pesados\u00bb del equipo y tambi\u00e9n en la salida de los futbolistas que no ser\u00e1n tomados en cuenta por Koeman.<\/p>\n\n\n\n<p>\u00abAmbos temas son clave para poder rebajar el excedente de masa salarial que existe en este momento, que impide inscribir a los nuevos fichajes y afecta a la situaci\u00f3n de Messi\u00bb, agreg\u00f3 el diario deportivo espa\u00f1ol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El club Barcelona espera llegar a un acuerdo con Lionel Messi durante los pr\u00f3ximos d\u00edas y contar con el astro argentino a partir del pr\u00f3ximo 8 de agosto, seg\u00fan se\u00f1ala hoy la prensa espa\u00f1ola. El presidente del club catal\u00e1n, Joan Laporta, reiter\u00f3 en las \u00faltimas horas que las tratativas para el nuevo contrato con Messi &hellip;<\/p>\n","protected":false},"author":2,"featured_media":6792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,15],"tags":[],"class_list":["post-35325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-deportes"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/05\/messi-estelada-camp-nou-barca-valladolid-efe-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/35325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=35325"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/35325\/revisions"}],"predecessor-version":[{"id":35326,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/35325\/revisions\/35326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/6792"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=35325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=35325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=35325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}