{"id":32540,"date":"2021-07-09T09:58:58","date_gmt":"2021-07-09T12:58:58","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=32540"},"modified":"2021-07-09T14:24:45","modified_gmt":"2021-07-09T17:24:45","slug":"victor-rea-patria-es-el-sentimiento-profundo-de-los-que-lucharon-y-luchan-para-construir-la-patria-grande","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/07\/09\/victor-rea-patria-es-el-sentimiento-profundo-de-los-que-lucharon-y-luchan-para-construir-la-patria-grande\/","title":{"rendered":"V\u00edctor Rea: \u201cPatria es el sentimiento profundo de los que lucharon y luchan para construir la Patria grande\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El intendente de Puerto Vilelas record\u00f3 el 205\u00ba aniversario de la Declaraci\u00f3n de la Independencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-32541\" style=\"width: 150px;\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0006.jpg\" alt=\"\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0006.jpg 1152w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0006-300x200.jpg 300w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0006-1024x683.jpg 1024w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0006-768x512.jpg 768w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco del 205\u00ba aniversario de la Declaraci\u00f3n de la Independencia que se conmemora este 9 de Julio, el intendente de Puerto Vilelas V\u00edctor Rea llam\u00f3 a la reflexi\u00f3n y a \u201chacer patria todos los d\u00edas, donde debemos destacar el esp\u00edritu y las fuerzas de la independencia nacional que se marca en la representaci\u00f3n de una patria grande\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"78\" class=\"wp-image-32543\" style=\"width: 150px;\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0007.jpg\" alt=\"\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0007.jpg 1280w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0007-300x155.jpg 300w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0007-1024x530.jpg 1024w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0007-768x398.jpg 768w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0007-390x205.jpg 390w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En sinton\u00eda a esto, el jefe comunal vilelense remarc\u00f3 que la \u201cPatria es el sentimiento profundo de los que lucharon y los que luchan todos los d\u00edas para construir la patria grande que so\u00f1aron nuestros patriotas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"100\" class=\"wp-image-32542\" style=\"width: 150px;\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0005.jpg\" alt=\"\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0005.jpg 1152w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0005-300x200.jpg 300w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0005-1024x683.jpg 1024w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0005-768x512.jpg 768w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, V\u00edctor Rea asent\u00f3 que la independencia tiene valor desde el punto de vista del ejercicio aut\u00f3nomo de las decisiones. En este sentido, expres\u00f3 que \u201cno hay soberan\u00eda pol\u00edtica sin independencia econ\u00f3mica al servicio de la voluntad popular y sin justicia social\u201d, remarcando a su vez que \u201cestos tres principios son esenciales para lograr la grandeza de la patria y la felicidad del pueblo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Puerto Vilelas record\u00f3 el 205\u00ba aniversario de la Declaraci\u00f3n de la Independencia. En el marco del 205\u00ba aniversario de la Declaraci\u00f3n de la Independencia que se conmemora este 9 de Julio, el intendente de Puerto Vilelas V\u00edctor Rea llam\u00f3 a la reflexi\u00f3n y a \u201chacer patria todos los d\u00edas, donde debemos destacar &hellip;<\/p>\n","protected":false},"author":2,"featured_media":32576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,14],"tags":[],"class_list":["post-32540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-politica"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/IMG-20210709-WA0063.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=32540"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32540\/revisions"}],"predecessor-version":[{"id":32545,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32540\/revisions\/32545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/32576"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=32540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=32540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=32540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}