{"id":32472,"date":"2021-07-08T17:54:05","date_gmt":"2021-07-08T20:54:05","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=32472"},"modified":"2021-07-08T17:54:09","modified_gmt":"2021-07-08T20:54:09","slug":"el-gobierno-y-el-nbch-firmaron-un-convenio-en-beneficio-de-mujeres-y-personas-lgbit","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/07\/08\/el-gobierno-y-el-nbch-firmaron-un-convenio-en-beneficio-de-mujeres-y-personas-lgbit\/","title":{"rendered":"El Gobierno y el NBCh firmaron un convenio en beneficio de mujeres y personas LGBIT+"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este jueves, el Gobierno firm\u00f3 un convenio con el presidente y la directora del Nuevo Banco del Chaco,&nbsp;Federico Mu\u00f1oz Femen\u00eda y Maia Woelfin, para la creaci\u00f3n de cuentas de ahorro para mujeres y personas LGBIT+ destinatarias del \u201cPrograma de Apoyo y Acompa\u00f1amiento a Personas en Situaci\u00f3n de Riesgo por Violencia por Motivos de G\u00e9nero &#8211; Acompa\u00f1ar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La iniciativa surgi\u00f3 luego de que el diagn\u00f3stico realizado para la puesta en marcha del programa, detectara que muchas beneficiaras no contaban con cuentas bancarias para percibir la ayuda econ\u00f3mica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El convenio incluye adem\u00e1s capacitaciones gratuitas para una real inclusi\u00f3n financiera. \u201cIniciativas de este tipo son una prioridad impostergable para el Estado en virtud de las condiciones socioecon\u00f3micas y vinculares a las que se encuentran expuestas las mujeres y personas LGBTI+\u201d, subray\u00f3 la vicegobernadora Anal\u00eda Rach Quiroga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, consider\u00f3 imprescindible facilitar las herramientas que permitan la recuperaci\u00f3n y fortalecimiento de las relaciones sociales y comunitarias en las que se insertan sus proyectos de vida, garantizando de manera plena el derecho a una vida libre de violencias.<strong>&nbsp;\u201cLa aplicaci\u00f3n de esta pol\u00edtica p\u00fablica responde a la clara concepci\u00f3n de un Estado presente y cercano\u201d, apunt\u00f3.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00e9rez inform\u00f3 que todas las v\u00edctimas de violencias por motivos de g\u00e9nero pueden asesorarse sobre el programa y sus beneficios en las \u00e1reas de g\u00e9neros de los municipios y de la Provincia.&nbsp;<strong>\u201cCon el NBCh pensamos este convenio para permitir el acceso a un derecho que hab\u00eda sido vulnerado hist\u00f3ricamente y asegurar as\u00ed la efectiva implementaci\u00f3n del programa Acompa\u00f1ar\u201d, sostuvo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompa\u00f1ar es un programa de asistencia integral que contempla no solo ayudas econ\u00f3micas e inserci\u00f3n laboral, sino tambi\u00e9n acompa\u00f1amiento social y psicol\u00f3gico.<strong>&nbsp;\u201cMuchas mujeres y diversidades est\u00e1n completamente excluidas del sistema econ\u00f3mico y la creaci\u00f3n de cuentas bancarias y capacitaci\u00f3n financiera permitir\u00e1 una real inclusi\u00f3n para que logren alcanzar su autonom\u00eda econ\u00f3mica. Por eso es imprescindible esta iniciativa para incluirlas al sistema financiero\u201d, culmin\u00f3.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La directora del Banco del Chaco record\u00f3 que la medida forma parte del plan de desarrollo inclusivo que lleva adelante la instituci\u00f3n bancaria en l\u00ednea con los objetivos del Estado. \u201cTodos y Todas deben formar parte de este proceso de desarrollo, sobre todo las personas m\u00e1s vulneradas en sus derechos. Con la creaci\u00f3n r\u00e1pida y gratuita de cuentas bancarias y la capacitaci\u00f3n financiera buscamos ponerlas en igualdad de condiciones y que puedan tener autonom\u00eda\u201d, destac\u00f3 y se\u00f1al\u00f3 que es una forma tambi\u00e9n de acercar el banco a la gente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Programa Acompa\u00f1ar<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Programa Acompa\u00f1ar se enmarca dentro del Plan Nacional de Acci\u00f3n contra las Violencias por Motivos de G\u00e9nero 2020-2022 del Ministerio de las Mujeres, G\u00e9neros y Diversidad de la Naci\u00f3n. Promueve la autonom\u00eda de las mujeres y personas LGBTI+ que se encuentran en riesgo acreditado por situaci\u00f3n de violencia por motivos de g\u00e9nero, mediante el otorgamiento de una prestaci\u00f3n econ\u00f3mica y el fortalecimiento de redes de acompa\u00f1amiento, cubriendo los gastos esenciales de organizaci\u00f3n y desarrollo de un proyecto de vida aut\u00f3nomo y libre de violencia. Consiste en el otorgamiento de un apoyo econ\u00f3mico correspondiente al valor de un salario m\u00ednimo vital y m\u00f3vil por un periodo de seis meses, por \u00fanica vez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves, el Gobierno firm\u00f3 un convenio con el presidente y la directora del Nuevo Banco del Chaco,&nbsp;Federico Mu\u00f1oz Femen\u00eda y Maia Woelfin, para la creaci\u00f3n de cuentas de ahorro para mujeres y personas LGBIT+ destinatarias del \u201cPrograma de Apoyo y Acompa\u00f1amiento a Personas en Situaci\u00f3n de Riesgo por Violencia por Motivos de G\u00e9nero &#8211; &hellip;<\/p>\n","protected":false},"author":2,"featured_media":32473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28,5],"tags":[],"class_list":["post-32472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-chaco"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/07\/d9bd7584-73d6-4cb6-8380-a81f5ba01db9.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=32472"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32472\/revisions"}],"predecessor-version":[{"id":32474,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32472\/revisions\/32474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/32473"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=32472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=32472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=32472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}