{"id":31247,"date":"2021-06-27T15:39:18","date_gmt":"2021-06-27T18:39:18","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=31247"},"modified":"2021-06-27T15:39:21","modified_gmt":"2021-06-27T18:39:21","slug":"clases-presenciales-se-conoce-el-nuevo-esquema-para-el-retorno-progresivo-hasta-el-2-de-julio","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/06\/27\/clases-presenciales-se-conoce-el-nuevo-esquema-para-el-retorno-progresivo-hasta-el-2-de-julio\/","title":{"rendered":"Clases presenciales: se conoce el nuevo esquema para el retorno progresivo hasta el 2 de julio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Ministerio de Educaci\u00f3n informa las actualizaciones en el r\u00e9gimen de presencialidad en las escuelas de la provincia para la semana del lunes 28 de junio al viernes 2 de julio, en virtud del Decreto 1242\/21 y la Resoluci\u00f3n 3242\/21. El esquema se divide en presencialidad cuidada, presencialidad restringida y bloque focal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Presencialidad restringida<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En localidades del interior provincial y barrios del \u00c1rea Metropolitana del Gran Resistencia que registran m\u00e1s de 500 casos cada 100.000 habitantes, los establecimientos quedan incluidos en el grupo de Escuelas con restricciones, y solo asistir\u00e1n presencialmente los grupos priorizados en la Resoluci\u00f3n del Consejo Federal de Educaci\u00f3n (CFE) N\u00ba 386.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos grupos priorizados son: las poblaciones escolares que por distintos factores no hayan podido mantener su continuidad pedag\u00f3gica; las ni\u00f1as y ni\u00f1os de sala de 4 y 5 a\u00f1os del Nivel Inicial, del primer ciclo y de 7\u00ba grado del Nivel Primario, estudiantes de ciclo b\u00e1sico y \u00faltimo a\u00f1o del Nivel Secundario, y estudiantes con discapacidad que no formen parte de los grupos de riesgo. Adem\u00e1s a partir de este nuevo memo se suman a este grupo los y las estudiantes que deban cumplir con los trayectos de pr\u00e1cticas en el Nivel Superior, Nivel Secundario (todas las modalidades) y Formaci\u00f3n Profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los dem\u00e1s grupos tendr\u00e1n acompa\u00f1amiento virtual a trav\u00e9s de la Plataforma &#8216;ELE&#8217; y otros entornos virtuales de aprendizaje. La creaci\u00f3n de aulas propias en &#8216;ELE&#8217; ser\u00e1 obligatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las localidades comprendidas en este grupo hasta el viernes 2 de julio son: Capit\u00e1n Solari, Charata, Colonia Ben\u00edtez, Colonia Popular, Colonias Unidas, Coronel Du Graty, Corzuela, Gancedo, General Vedia, La Escondida, Laguna Blanca, Lapachito, Las Bre\u00f1as, Las Garcitas, Machagai, Makall\u00e9. Margarita Bel\u00e9n, Pampa del Infierno, Presidencia Roca, Puerto Tirol, Quitilipi, R\u00edo Muerto S\u00e1enz Pe\u00f1a, Villa \u00c1ngela y Villa R\u00edo Bermejito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los barrios de Resistencia con presencialidad restringida hasta el 2 de julio son los siguientes: Villa Aeropuerto, Vargas II, Central Norte, Centro 3 (delimitado por las avenidas Alberdi, Alvear, Hernandarias\/Avalos, Lavalle\/Laprida, V\u00e9lez Sarsfield y 9 de Julio), Golf Club, Palermo I y II, Plan 96 Viviendas SEJCH, Plan 56 Viviendas SEJCH, Roger Balet, Villa 25 de Mayo y Pezzini, Santo Domingo, Villa Adelante, Villa \u00c1valos,Villa Centenario, Villa del Oeste, Villa Don Alberto, Villa Don Enrique, Villa Don Rafael, Villa Donovan, Villa El Dorado, Villa El Tala, Villa Elisa, Villa Encarnaci\u00f3n, Villa Facundo, Villa General Mitre, Juan de Garay, Villa Libertad, Villa Los Lirios, Villa Mariano Moreno, Villa Odorico, Villa Perrando, Villa Prosperidad, Villa San Juan y Villa Teniente Saavedra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Barranqueras estar\u00e1n bajo presencialidad restringida las instituciones educativas de los barrios La Toma, Florida Norte, Las Malvinas y 75 Viviendas. En Fontana suceder\u00e1 lo propio en los barrios Nueva Provincia, Villa Sarmiento, Barrio Jos\u00e9 Hern\u00e1ndez y Villa All\u00edn. En Puerto Vilelas, en los barrios 150 Viviendas y 60 Viviendas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Bloqueo Focal<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las Escuelas bajo bloqueo focal ser\u00e1n establecimientos de cualquier nivel y modalidad de localidades que presenten crecimiento inter-quincenal de la tasa de incidencia Covid-19 mayor al 20%, o cuyos Comit\u00e9s de Emergencia locales decidan la interrupci\u00f3n total de actividades presenciales, as\u00ed como las escuelas con m\u00e1s de tres burbujas con casos activos en simult\u00e1neo. En estas instituciones se suspender\u00e1n las actividades presenciales; las y los docentes deber\u00e1n dar continuidad al desarrollo curricular a trav\u00e9s del dictado de clases de manera digital, utilizando la plataforma ELE y otros entornos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las localidades bajo bloqueo focal hasta el 2 de julio son: Basail, General Capdevila, Tres Mojones, Concepci\u00f3n del Bermejo, Colonia Aborigen, Cote Lai, Fuerte Esperanza, General Pinedo, Hermoso Campo, It\u00edn, Isla del Cerrito, Castelli, La Verde, Los Frentones, Mes\u00f3n de Fierro, Palmar, Pampa Landiel, Samuhu, San Bernardo, Taco Pozo, Tres Isletas y Villa Berthet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Presencialidad cuidada<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Todas las dem\u00e1s unidades educativas de la provincia que no clasifiquen como \u201cEscuelas con Restricciones\u201d o \u201cEscuelas con Bloqueo Focal\u201d, incluyendo la totalidad de establecimientos del \u00e1mbito rural, desarrollar\u00e1n sus clases presenciales cuidadas con la totalidad de sus estudiantes, siguiendo el protocolo establecido por Decreto 355\/21. El r\u00e9gimen actual aplica a la modalidad de educaci\u00f3n en contexto de encierro, seg\u00fan la localidad\/barrio en la que se encuentre el servicio educativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se recuerda que los establecimientos educativos deber\u00e1n conservar una guardia m\u00ednima, garantizando el acceso a los dispositivos electr\u00f3nicos y la conectividad. Los docentes que no posean medios digitales conectados y deban cumplir su jornada laboral de manera remota deber\u00e1n asistir al establecimiento, usando las herramientas all\u00ed disponibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades de cada escuela deber\u00e1n informar, tanto a la Direcci\u00f3n Regional como a la Regional Sanitaria, sobre la adopci\u00f3n de este protocolo, ya sea para la suspensi\u00f3n o para la continuidad de la presencialidad. Se recuerda tambi\u00e9n la obligatoriedad de la carga de casos epidemiol\u00f3gicamente relevantes en la Plataforma Cuidar Escuelas (<a href=\"http:\/\/argentina.gob.ar\/cuidarescuelas\" target=\"_blank\" rel=\"noreferrer noopener\">argentina.gob.ar\/cuidarescuelas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Educaci\u00f3n informa las actualizaciones en el r\u00e9gimen de presencialidad en las escuelas de la provincia para la semana del lunes 28 de junio al viernes 2 de julio, en virtud del Decreto 1242\/21 y la Resoluci\u00f3n 3242\/21. El esquema se divide en presencialidad cuidada, presencialidad restringida y bloque focal. Presencialidad restringida En &hellip;<\/p>\n","protected":false},"author":2,"featured_media":31248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,12],"tags":[],"class_list":["post-31247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-ultimo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/06\/clases.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31247"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31247\/revisions"}],"predecessor-version":[{"id":31249,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31247\/revisions\/31249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/31248"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}