{"id":30913,"date":"2021-06-23T20:44:45","date_gmt":"2021-06-23T23:44:45","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=30913"},"modified":"2021-06-23T20:44:47","modified_gmt":"2021-06-23T23:44:47","slug":"encontraron-muerto-a-john-mcafee-el-creador-del-antivirus","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/06\/23\/encontraron-muerto-a-john-mcafee-el-creador-del-antivirus\/","title":{"rendered":"Encontraron muerto a John McAfee, el creador del antivirus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El empresario brit\u00e1nico John\u00a0McAfee\u00a0fue encontrado muerto en una celda de una prisi\u00f3n catalana, luego de que la Audiencia Nacional de Espa\u00f1a autorizara su extradici\u00f3n a EEUU, inform\u00f3 el departamento de justicia regional de Barcelona. Todo apunta a que el creador del software antivirus, de 75 a\u00f1os,\u00a0<strong>se habr\u00eda suicidado<\/strong>, agreg\u00f3 la cartera.\u00a0El tribunal superior hab\u00eda acordado extraditarlo a EEUU, donde enfrentaba cargos por evasi\u00f3n de impuestos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">McAfee, que en los \u00faltimos a\u00f1os se hab\u00eda dedicado a comerciar criptomonedas,\u00a0fue detenido en octubre pasado en el aeropuerto de Barcelona, y puesto en prisi\u00f3n preventiva a la espera de que se resolviera el pedido de extradici\u00f3n. La decisi\u00f3n de la Audiencia Nacional espa\u00f1ola no estaba firma y a\u00fan pod\u00eda ser recurrida. McAfee se enfrentaba a una pena de hasta 30 a\u00f1os de c\u00e1rcel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades norteamericanas solicitaron la extradici\u00f3n alegando que McAfee gan\u00f3 m\u00e1s de diez millones de d\u00f3lares entre 2014 y 2018 gracias a la actividad con criptomonedas, servicios de consultor\u00eda, conferencias y la venta de derechos para la realizaci\u00f3n de un documental sobre su vida. Sin embargo, \u00abno present\u00f3 declaraciones de impuestos durante ninguno de esos a\u00f1os y no pag\u00f3 ninguna de sus obligaciones fiscales\u00bb, seg\u00fan recoge el auto de la Audiencia Nacional, un alto tribunal con sede en Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPara ocultar sus ingresos y activos\u00bb, el reclamado \u00aborden\u00f3 el pago de una parte de sus ingresos a testaferros y puso propiedades a nombre de estos\u00bb, a\u00f1ade el escrito citando la argumentaci\u00f3n de la administraci\u00f3n fiscal estadounidense, que estima la deuda del empresario en 4,2 millones de d\u00f3lares antes de multas e intereses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El empresario brit\u00e1nico John\u00a0McAfee\u00a0fue encontrado muerto en una celda de una prisi\u00f3n catalana, luego de que la Audiencia Nacional de Espa\u00f1a autorizara su extradici\u00f3n a EEUU, inform\u00f3 el departamento de justicia regional de Barcelona. Todo apunta a que el creador del software antivirus, de 75 a\u00f1os,\u00a0se habr\u00eda suicidado, agreg\u00f3 la cartera.\u00a0El tribunal superior hab\u00eda acordado &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[],"class_list":["post-30913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/06\/john-mcafeejpg.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=30913"}],"version-history":[{"count":2,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30913\/revisions"}],"predecessor-version":[{"id":30916,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30913\/revisions\/30916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/30914"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=30913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=30913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=30913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}