{"id":30381,"date":"2021-06-18T08:30:54","date_gmt":"2021-06-18T11:30:54","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=30381"},"modified":"2021-06-18T08:31:30","modified_gmt":"2021-06-18T11:31:30","slug":"conoce-como-continua-la-aplicacion-de-segundas-dosis-de-la-vacunacion-contra-covid-19","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/06\/18\/conoce-como-continua-la-aplicacion-de-segundas-dosis-de-la-vacunacion-contra-covid-19\/","title":{"rendered":"Conoc\u00e9 c\u00f3mo continua la aplicaci\u00f3n de segundas dosis de la vacunaci\u00f3n contra Covid-19"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La provincia del Chaco super\u00f3 las 488 mil dosis aplicadas de vacunas contra la COVID-19. En este contexto, la campa\u00f1a provincial de vacunaci\u00f3n continuar\u00e1 este viernes 18 de junio en distintos lugares del Chaco, por lo que el Ministerio de Salud P\u00fablica dio a conocer el cronograma de vacunaci\u00f3n contra coronavirus previsto hoy con el siguiente detalle:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cronograma de vacunaci\u00f3n contra COVID-19 del viernes&nbsp;18 de junio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-Segundo componente de Sputnik V para personas de entre 75 a 79 a\u00f1os, con terminaci\u00f3n de DNI 9<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resistencia: Centro de Convenciones Gala y Sede UNNE (Av. Las Heras 729, Aula Magna), de 8 a 15:30.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-Personas mayores de 30 a\u00f1os, para aplicaci\u00f3n de primeras dosis, sin turnos. Tambi\u00e9n segundas dosis de AstraZeneca (para quienes cumplieron 8 semanas de aplicaci\u00f3n de la primera dosis)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Resistencia:<\/em>&nbsp;Club Sarmiento, Club Chaco For Ever, Club Central Norte, Parque de la Democracia, Escuela de Salud P\u00fablica y&nbsp; Polideportivo Jaime Zapata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Barranqueras<\/em>: Centro Cultural La Flota<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Puerto Vilelas<\/em>: Casa de las Culturas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Fontana<\/em>: Auditorio Tepeyac<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De 8 a 15:30.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-Personal docente (Aplicaci\u00f3n de primeras dosis a personas correspondiente al memo 42 del Ministerio de Educaci\u00f3n)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sede del Ej\u00e9rcito Argentino de Resistencia (Av. 9 de julio 3.300), de 7 a 13.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-Vacunaciones domiciliarias. Quienes solicitaron la misma, recibir\u00e1n un llamado telef\u00f3nico desde este Ministerio para coordinar visita.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La provincia del Chaco super\u00f3 las 488 mil dosis aplicadas de vacunas contra la COVID-19. En este contexto, la campa\u00f1a provincial de vacunaci\u00f3n continuar\u00e1 este viernes 18 de junio en distintos lugares del Chaco, por lo que el Ministerio de Salud P\u00fablica dio a conocer el cronograma de vacunaci\u00f3n contra coronavirus previsto hoy con el &hellip;<\/p>\n","protected":false},"author":2,"featured_media":30382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,46],"tags":[],"class_list":["post-30381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-salud"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/06\/FB_IMG_1624015741779.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=30381"}],"version-history":[{"count":2,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30381\/revisions"}],"predecessor-version":[{"id":30384,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/30381\/revisions\/30384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/30382"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=30381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=30381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=30381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}