{"id":22318,"date":"2021-03-14T14:08:30","date_gmt":"2021-03-14T17:08:30","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=22318"},"modified":"2021-03-14T14:08:35","modified_gmt":"2021-03-14T17:08:35","slug":"buscan-declarar-como-reserva-natural-a-la-laguna-el-palmar","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/03\/14\/buscan-declarar-como-reserva-natural-a-la-laguna-el-palmar\/","title":{"rendered":"Buscan declarar como reserva natural a la laguna El Palmar"},"content":{"rendered":"\n<p>El Gobierno provincial trabaja para que la laguna El Palmar sea declarada reserva o parque natural. En ese marco, la secretaria Marta Soneira junto al presidente de la C\u00e1mara de Diputados Hugo Sager e intendentes de la zona, recorrieron el lugar y mantuvieron una reuni\u00f3n con el fin de aunar criterios e impulsar la meta propuesta.<\/p>\n\n\n\n<p>\u201cEste lugar cuenta con una gran diversidad biol\u00f3gica y representa uno de los ecosistemas identitarios de nuestro Chaco\u00bb, coment\u00f3 Soneira.<\/p>\n\n\n\n<p>La laguna El Palmar cuenta con una superficie de casi 5.000 hect\u00e1reas, de las cuales m\u00e1s de 3.000 est\u00e1n conformadas por un gran espejo de agua que se abastece de lluvias, acu\u00edferos y del r\u00edo Paraguay en los momentos de crecida.<\/p>\n\n\n\n<p>En el marco del Consejo Provincial del Ambiente y a trav\u00e9s de la comisi\u00f3n de \u00c1reas Protegidas y Reservas Urbanas, se busca impulsar junto a la sociedad chaque\u00f1a e instituciones la creaci\u00f3n de la Reserva o Parque Natural Laguna El Palmar.<\/p>\n\n\n\n<p>\u201cLa propuesta tiene como objetivo fomentar la conservaci\u00f3n de la laguna por su biodiversidad, conectarla con los sitios Ramsar y humedales de importancia en la Provincia, integr\u00e1ndola as\u00ed al paisaje local y al desarrollo de actividades que generan empleo y valor\u00bb, se\u00f1al\u00f3 Soneira.<\/p>\n\n\n\n<p>A su turno, el presidente de la legislatura chaque\u00f1a, Hugo Sager, destac\u00f3 la iniciativa y la necesidad de un proyecto conjunto \u201cpara conservar este gran espejo de agua y la magn\u00edfica flora y fauna de la zona. Es necesario controlar y regular la presencia humana, por lo que vinimos a acompa\u00f1ar, trabajar en forma conjunta y en la legislaci\u00f3n correspondiente\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>A su turno, la responsable de Relaciones Institucionales de la Secretar\u00eda de Desarrollo Territorial y Ambiente, Liliana Jara, destac\u00f3: \u201cEl gobernador est\u00e1 en conocimiento del proyecto de ley y de todo lo que se est\u00e1 trabajando en pol\u00edticas ambientales\u201d, remarc\u00f3 y adelant\u00f3 que pr\u00f3ximamente arribar\u00e1 a Chaco el ministro de Ambiente y Desarrollo Sostenible de la Naci\u00f3n, Juan Cabandi\u00e9, para ser part\u00edcipe y darle impulso a la iniciativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno provincial trabaja para que la laguna El Palmar sea declarada reserva o parque natural. En ese marco, la secretaria Marta Soneira junto al presidente de la C\u00e1mara de Diputados Hugo Sager e intendentes de la zona, recorrieron el lugar y mantuvieron una reuni\u00f3n con el fin de aunar criterios e impulsar la meta &hellip;<\/p>\n","protected":false},"author":2,"featured_media":22319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,3],"tags":[],"class_list":["post-22318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/03\/604e1f07d55db015555959.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=22318"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22318\/revisions"}],"predecessor-version":[{"id":22320,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22318\/revisions\/22320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/22319"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=22318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=22318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=22318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}