{"id":20557,"date":"2021-02-09T19:57:39","date_gmt":"2021-02-09T22:57:39","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=20557"},"modified":"2021-02-09T19:57:42","modified_gmt":"2021-02-09T22:57:42","slug":"resistencia-una-joven-fue-detenida-por-robar-en-un-local-de-ropa-deportiva","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2021\/02\/09\/resistencia-una-joven-fue-detenida-por-robar-en-un-local-de-ropa-deportiva\/","title":{"rendered":"Resistencia: Una joven fue detenida por robar en un local de ropa deportiva"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un hombre denunci\u00f3 en la Comisar\u00eda Octava de Resistencia que en su local comercial de ropas, ubicado por la calle Monteagudo al 800 aproximadamente, sustrajeron prendas de vestir deportivas. Con los datos aportados por el ciudadano los efectivos desplegaron tareas investigativas y dieron intervenci\u00f3n al Servicio Externo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan se informa desde la Polic\u00eda del Chaco, esta ma\u00f1ana, los agentes obtuvieron informaci\u00f3n precisa que una mujer intentaba vender la vestimenta por la zona de Villa San Mart\u00edn. Orientaron sus patrullajes hacia dicho lugar. Por la calle Monteagudo al 900, demoraron a una ciudadana que transportaba varios bolsos. La identificaron y solicitaron que exhiba lo que llevaba. De esta forma dieron cuenta que en su poder ten\u00eda remeras y dinero en efectivo. Las prendas coincid\u00edan con las buscadas, labraron acta de secuestro de 61 remeras y la suma de 280 pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente se dio intervenci\u00f3n a la Fiscal\u00eda en turno y la conducida de 22 a\u00f1os fue notificada de su detenci\u00f3n en la causa Supuesto Encubrimiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre denunci\u00f3 en la Comisar\u00eda Octava de Resistencia que en su local comercial de ropas, ubicado por la calle Monteagudo al 800 aproximadamente, sustrajeron prendas de vestir deportivas. Con los datos aportados por el ciudadano los efectivos desplegaron tareas investigativas y dieron intervenci\u00f3n al Servicio Externo. Seg\u00fan se informa desde la Polic\u00eda del Chaco, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":20558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,37],"tags":[],"class_list":["post-20557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2021\/02\/8e2e528c-5a32-4952-9746-435c7971a2c0.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=20557"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20557\/revisions"}],"predecessor-version":[{"id":20559,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20557\/revisions\/20559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/20558"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=20557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=20557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=20557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}