{"id":16589,"date":"2020-12-08T08:45:28","date_gmt":"2020-12-08T11:45:28","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=16589"},"modified":"2020-12-08T08:45:30","modified_gmt":"2020-12-08T11:45:30","slug":"aborto-legal-feministas-convocan-a-una-jornada-de-vigilia-frente-al-congreso","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/12\/08\/aborto-legal-feministas-convocan-a-una-jornada-de-vigilia-frente-al-congreso\/","title":{"rendered":"Aborto legal: feministas convocan a una jornada de vigilia frente al Congreso"},"content":{"rendered":"\n<p>La\u00a0Campa\u00f1a Nacional por el Derecho al\u00a0Aborto\u00a0Legal, Seguro y Gratuito\u00a0convoc\u00f3 a una vigilia en inmediaciones del\u00a0Congreso\u00a0de la Naci\u00f3n y en distintas ciudades del pa\u00eds \u201crumbo a una conquista hist\u00f3rica\u201d para los pr\u00f3ximos 10 y 11 de diciembre.<\/p>\n\n\n\n<p>La C\u00e1mara de\u00a0Diputados\u00a0\u201cdebatir\u00e1 y votar\u00e1 la Ley de Interrupci\u00f3n Voluntaria del Embarazo y desde la Campa\u00f1a Nacional por el Derecho al Aborto Legal, Seguro y Gratuito convocamos a una vigilia en inmediaciones al Congreso de la Naci\u00f3n y en distintas ciudades del pa\u00eds rumbo a una conquista hist\u00f3rica\u201d explicaron esta tarde bajo la consigna \u201c\u00a1Con la alegr\u00eda como bandera!\u201d.<\/p>\n\n\n\n<p>La convocatoria es&nbsp;desde el pr\u00f3ximo jueves a las 10 de la ma\u00f1ana.<\/p>\n\n\n\n<p>\u201c<strong>Se espera una jornada extensa, ya que ser\u00e1n aproximadamente 30 horas de debate que acompa\u00f1aremos con actividades y talleres<\/strong>. Habr\u00e1 un escenario central y pantallas sobre las calles Rivadavia y Callao para que, quienes se acerquen, puedan seguir las intervenciones de las y los diputados\u201d, afirmaron a trav\u00e9s de un comunicado de prensa que compartieron en las redes sociales.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/12\/fc93c341-e2bc-4238-b368-44e5b228923b.jpg\" alt=\"\" class=\"wp-image-16590\" width=\"656\" height=\"981\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/12\/fc93c341-e2bc-4238-b368-44e5b228923b.jpg 408w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/12\/fc93c341-e2bc-4238-b368-44e5b228923b-201x300.jpg 201w\" sizes=\"auto, (max-width: 656px) 100vw, 656px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0Campa\u00f1a Nacional por el Derecho al\u00a0Aborto\u00a0Legal, Seguro y Gratuito\u00a0convoc\u00f3 a una vigilia en inmediaciones del\u00a0Congreso\u00a0de la Naci\u00f3n y en distintas ciudades del pa\u00eds \u201crumbo a una conquista hist\u00f3rica\u201d para los pr\u00f3ximos 10 y 11 de diciembre. La C\u00e1mara de\u00a0Diputados\u00a0\u201cdebatir\u00e1 y votar\u00e1 la Ley de Interrupci\u00f3n Voluntaria del Embarazo y desde la Campa\u00f1a Nacional por el &hellip;<\/p>\n","protected":false},"author":2,"featured_media":16327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[14],"tags":[],"class_list":["post-16589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/12\/B97.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16589"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16589\/revisions"}],"predecessor-version":[{"id":16591,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16589\/revisions\/16591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/16327"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}