{"id":16132,"date":"2020-11-28T15:14:47","date_gmt":"2020-11-28T18:14:47","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=16132"},"modified":"2020-11-28T15:14:51","modified_gmt":"2020-11-28T18:14:51","slug":"se-realizara-colecta-de-sangre-en-distintas-localidades-en-diciembre","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/11\/28\/se-realizara-colecta-de-sangre-en-distintas-localidades-en-diciembre\/","title":{"rendered":"Se realizar\u00e1 colecta de sangre en distintas localidades en diciembre"},"content":{"rendered":"\n<p>Durante el mes de diciembre el Ministerio de Salud P\u00fablica del Chaco, a trav\u00e9s del Centro Provincial de Hemoterapia, realizar\u00e1 colectas voluntarias de sangre en postas dispuestas en distintas localidades de la provincia. En las jornadas las personas interesadas tambi\u00e9n podr\u00e1n inscribirse en el Registro Nacional de Donantes de M\u00e9dula \u00d3sea.<\/p>\n\n\n\n<p>El s\u00e1bado 12 de diciembre se ubicar\u00e1 en el SUM de la ciudad de Gancedo, de 8 a 12. Mientras que el 19 de diciembre se har\u00e1 de manera simult\u00e1nea en el Centro Comunitario de Puerto Vilelas y en el Club Social y Deportivo El Fort\u00edn de Machagai; en ambos casos tambi\u00e9n de 8 a 12.<\/p>\n\n\n\n<p>Para donar sangre los voluntarios y las voluntarias deben cumplir con los requisitos dispuestos en la Ley Nacional de Donaci\u00f3n de Sangre: tener entre 18 y 60 a\u00f1os (en el caso de donaci\u00f3n de m\u00e9dula \u00f3sea la edad es de entre 18 y 40 a\u00f1os), no poseer patolog\u00edas de base, pesar m\u00e1s de 50 kilos, no contar haberse realizado tatuajes y\/o piercings en el \u00faltimo a\u00f1o y no realizar pr\u00e1cticas sexuales de riesgo. Adem\u00e1s deber\u00e1n presentarse con DNI y no es necesario estar en ayunas.<\/p>\n\n\n\n<p>El Centro de Hemoterapia del hospital Perrando recibe en promedio entre 30 y 40 donantes de sangre por la ma\u00f1ana, y otros 10 m\u00e1s en horas de la tarde. \u201cEs de vital importancia la donaci\u00f3n de sangre porque es el insumo necesario para muchas otras \u00e1reas de la salud que contin\u00faan funcionando con normalidad durante la pandemia\u201d, se\u00f1al\u00f3 la especialista del \u00e1rea, J\u00e9sica Acu\u00f1a.<\/p>\n\n\n\n<p>\u201cDurante las primeras etapas de la pandemia de COVID-19 donde hubo una cuarentena m\u00e1s estricta, las donaciones de sangre y m\u00e9dula \u00f3sea disminuyeron un 80% en todo el pa\u00eds. Ante esta situaci\u00f3n tuvimos que implementar diversas estrategias como postas de extracci\u00f3n en escuelas o puntos m\u00f3viles en distintas zonas de la ciudad o localidades, lo que nos permiti\u00f3 ir progresivamente normalizando el acercamiento de los donantes voluntarios\u201d, cont\u00f3 la profesional.<\/p>\n\n\n\n<p>Las personas interesadas en la donaci\u00f3n de sangre y\/o de m\u00e9dula \u00f3sea tambi\u00e9n pueden dirigirse al Centro Provincial de Hemoterapia del Chaco del Hospital Perrando, ubicado sobre la avenida 9 de Julio al 1.100 de Resistencia, de lunes a viernes de 7 a 12. Tambi\u00e9n pueden comunicarse al 3794-810071 o en los perfiles \u201cCentro Provincial de Hemoterapia\u201d de Facebook y \u201cChaco Dona Sangre\u201d en Instagram. Asimismo, tambi\u00e9n se puede donar sangre y m\u00e9dula \u00f3sea en las postas ubicadas en los hospitales de las localidades de San Mart\u00edn, Charata, S\u00e1enz Pe\u00f1a y Castelli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el mes de diciembre el Ministerio de Salud P\u00fablica del Chaco, a trav\u00e9s del Centro Provincial de Hemoterapia, realizar\u00e1 colectas voluntarias de sangre en postas dispuestas en distintas localidades de la provincia. En las jornadas las personas interesadas tambi\u00e9n podr\u00e1n inscribirse en el Registro Nacional de Donantes de M\u00e9dula \u00d3sea. El s\u00e1bado 12 de &hellip;<\/p>\n","protected":false},"author":2,"featured_media":16133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5,46],"tags":[],"class_list":["post-16132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-salud"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/11\/35c79adc2cbc0983c6e3c3a6bf158c52.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16132"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16132\/revisions"}],"predecessor-version":[{"id":16134,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16132\/revisions\/16134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/16133"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}