{"id":15671,"date":"2020-11-18T12:14:17","date_gmt":"2020-11-18T15:14:17","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=15671"},"modified":"2020-11-18T12:14:19","modified_gmt":"2020-11-18T15:14:19","slug":"pondran-en-marcha-la-logistica-de-vacunacion-contra-el-covid-19-en-el-pais","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/11\/18\/pondran-en-marcha-la-logistica-de-vacunacion-contra-el-covid-19-en-el-pais\/","title":{"rendered":"Pondr\u00e1n en marcha \u00abla log\u00edstica de vacunaci\u00f3n\u00bb contra el Covid-19 en el pa\u00eds"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Alberto Ferm\u00e1ndez sostuvo hoy que convoc\u00f3 para el pr\u00f3ximo lunes al comit\u00e9 de vacunaci\u00f3n, que integran los ministerios de Salud, Defensa y Seguridad, para \u00abponer en marcha la log\u00edstica de vacunaci\u00f3n\u00bb contra el coronavirus, y ratific\u00f3 que el Gobierno espera \u00abempezar cuanto antes, entre fines de diciembre y los primeros d\u00edas de enero\u00bb con la aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl lunes se reunir\u00e1 el Comit\u00e9 de Vacunaci\u00f3n para poner en marcha la log\u00edstica de vacunaci\u00f3n, que queremos tener listo cuanto antes. Pero todo depende de que las vacunas sean aprobadas\u00bb, sostuvo el jefe de Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En declaraciones a<strong><em> A24<\/em><\/strong>, el mandatario remarc\u00f3 que \u00abel Estado va a concentrar la compra de todas las vacunas\u00bb contra el COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLo que tenemos que hacer es, antes que nada, vacunar a las personas en riesgo. Hemos tenido una cantidad de contagiados muy grandes, pero entre los fallecidos el promedio de edad es de 74 a\u00f1os\u00bb, explic\u00f3 Alberto Fern\u00e1ndez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Presidente indic\u00f3 que se est\u00e1 trabajando \u00abdenodadamente\u00bb para que la vacuna est\u00e9 disponible en la Argentina lo antes posible y consider\u00f3 que \u00abhubo una interpretaci\u00f3n malintencionada o embarrada\u00bb sobre lo que dijo de cu\u00e1ndo pod\u00eda llegar la vacuna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHubo una informaci\u00f3n mal intencionada de un portal sobre lo que dije de las vacunas. Me hicieron un reportaje en Chile y la pregunta fue cu\u00e1ndo iban a poder contar en Chile con la vacuna que fabricamos en la Argentina con M\u00e9xico, que es la vacuna de Oxford y AstraZ\u00e9neca. Yo dije que la vacuna iba a estar en marzo y que a partir de marzo se iba a poder distribuir en Latinoam\u00e9rica\u00bb, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y agreg\u00f3: \u00abEn ese plan nosotros estar\u00edamos recibiendo, creo, 4,5 millones de vacunas, lo que significa el 10 por ciento de la poblaci\u00f3n, por lo que cada pa\u00eds iba a recibir vacunas para vacunar al 10 por ciento de su poblaci\u00f3n. Ese fue el comentario. Nosotros estamos negociando con todos, con Rusia, China, Pfizer y Moderna\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Alberto Ferm\u00e1ndez sostuvo hoy que convoc\u00f3 para el pr\u00f3ximo lunes al comit\u00e9 de vacunaci\u00f3n, que integran los ministerios de Salud, Defensa y Seguridad, para \u00abponer en marcha la log\u00edstica de vacunaci\u00f3n\u00bb contra el coronavirus, y ratific\u00f3 que el Gobierno espera \u00abempezar cuanto antes, entre fines de diciembre y los primeros d\u00edas de enero\u00bb &hellip;<\/p>\n","protected":false},"author":2,"featured_media":15672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[34,12],"tags":[],"class_list":["post-15671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-ultimo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/11\/319317_cla.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/15671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=15671"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/15671\/revisions"}],"predecessor-version":[{"id":15673,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/15671\/revisions\/15673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/15672"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=15671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=15671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=15671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}