{"id":15364,"date":"2020-11-11T14:23:45","date_gmt":"2020-11-11T17:23:45","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=15364"},"modified":"2020-11-11T14:23:47","modified_gmt":"2020-11-11T17:23:47","slug":"anses-nego-que-este-confirmado-el-pago-del-ife-4","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/11\/11\/anses-nego-que-este-confirmado-el-pago-del-ife-4\/","title":{"rendered":"Anses neg\u00f3 que est\u00e9 confirmado el pago del IFE 4"},"content":{"rendered":"\n<p>La titular de la Administraci\u00f3n Nacional de la Seguridad Social (ANSeS),\u00a0Fernanda Raverta, neg\u00f3 este mi\u00e9rcoles que el gobierno de\u00a0Alberto Fern\u00e1ndez\u00a0haya confirmado un nuevo pago del\u00a0Ingreso Familiar de Emergencia (IFE)\u00a0y ratific\u00f3 que se est\u00e1 evaluando de qu\u00e9 manera podr\u00eda reconvertirse la prestaci\u00f3n creada al calor de la pandemia de coronavirus Covid-19.<\/p>\n\n\n\n<p>\u00abEl IFE fue un decreto para asistir por \u00fanica vez y excepcionalmente. Pero el presidente de la Naci\u00f3n tuvo que firmar tres decretos a medida que segu\u00eda habiendo dificultades\u00bb, dijo Raverta en declaraciones radiales.<\/p>\n\n\n\n<p>La funcionaria nacional se\u00f1al\u00f3 que no puede dar todav\u00eda una fecha que precise cu\u00e1ndo se va a saber si se pagar\u00e1 o no una cuarta versi\u00f3n del IFE de 10 mil pesos y agreg\u00f3 que&nbsp;\u00abse est\u00e1 evaluando porque la din\u00e1mica es bien compleja\u00bb.<\/p>\n\n\n\n<p>A pesar de ello aclar\u00f3 que&nbsp;el Gobierno \u00abno dejar\u00e1 de asistir\u00bb a los que menos recursos tienen&nbsp;ya que hay un ingreso universal que es para los chicos de cero a 18 a\u00f1os que lo cobran 2,4 millones de personas desde hace once a\u00f1os.<\/p>\n\n\n\n<p>Raverta hizo hincapi\u00e9 en que&nbsp;en esta etapa de \u00abnueva normalidad\u00bb, el foco del Gobierno est\u00e1 puesto en \u00abgenerar trabajo\u00bb,&nbsp;aunque reconoci\u00f3 que \u00abexisten sectores de la poblaci\u00f3n econ\u00f3micamente activa a los que les cuesta m\u00e1s reincorporarse\u00bb y por eso \u00abhay que pensar en pol\u00edticas de asistencia\u00bb.<\/p>\n\n\n\n<p>\u00abA m\u00ed me gusta decir que&nbsp;cuando pase la pandemia vamos a estar hablando mucho tiempo de lo que logramos hacer,&nbsp;como haber ganado tiempo para que el sistema sanitario est\u00e9 en condiciones pero que no explotara en t\u00e9rminos de ingresos familiares para las familias m\u00e1s pobres de la Argentina\u00bb, dijo.<\/p>\n\n\n\n<p>En cuanto a los haberes judiciales, mientras comienza el debate pol\u00edtico para definir la nueva f\u00f3rmula de movilidad jubilatorio. Hasta tanto entre en vigencia es el Gobierno el que de manera unilateral define las subas y Raverta confirm\u00f3 en di\u00e1logo con&nbsp;<em>C5N&nbsp;<\/em>que ya est\u00e1n analizando de qu\u00e9 manera se dar\u00e1 la pr\u00f3xima actualizaci\u00f3n de haberes previstos para diciembre pr\u00f3ximo. Aunque todav\u00eda est\u00e1 en estudio la mejora podr\u00eda darse por medio de un aumento, un bono o la combinaci\u00f3n de ambas opciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La titular de la Administraci\u00f3n Nacional de la Seguridad Social (ANSeS),\u00a0Fernanda Raverta, neg\u00f3 este mi\u00e9rcoles que el gobierno de\u00a0Alberto Fern\u00e1ndez\u00a0haya confirmado un nuevo pago del\u00a0Ingreso Familiar de Emergencia (IFE)\u00a0y ratific\u00f3 que se est\u00e1 evaluando de qu\u00e9 manera podr\u00eda reconvertirse la prestaci\u00f3n creada al calor de la pandemia de coronavirus Covid-19. \u00abEl IFE fue un decreto &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[175],"tags":[],"class_list":["post-15364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/07\/IFE_234_1592235852_1593520938_1594036005.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/15364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=15364"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/15364\/revisions"}],"predecessor-version":[{"id":15365,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/15364\/revisions\/15365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/8797"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=15364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=15364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=15364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}