{"id":13762,"date":"2020-10-08T22:54:56","date_gmt":"2020-10-09T01:54:56","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=13762"},"modified":"2020-10-08T22:54:59","modified_gmt":"2020-10-09T01:54:59","slug":"hallan-en-paraguay-un-helicoptero-que-alquilo-la-policia-bonaerense-en-gestion-de-maria-eugenia-vidal","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/10\/08\/hallan-en-paraguay-un-helicoptero-que-alquilo-la-policia-bonaerense-en-gestion-de-maria-eugenia-vidal\/","title":{"rendered":"Hallan en Paraguay un helic\u00f3ptero que alquil\u00f3 la Polic\u00eda Bonaerense en gesti\u00f3n de Mar\u00eda Eugenia Vidal"},"content":{"rendered":"\n<p>Un helic\u00f3ptero que hab\u00eda sido alquilado por el\u00a0Ministerio de Seguridad bonaerense\u00a0durante la gesti\u00f3n de Mar\u00eda Eugenia Vidal fue allanado en la ciudad paraguaya de Aregu\u00e1 en el marco de una investigaci\u00f3n contra un grupo criminal vinculado al tr\u00e1fico de drogas por v\u00eda a\u00e9rea.<\/p>\n\n\n\n<p>\u00abEncontramos ocho aeronaves m\u00e1s un helic\u00f3ptero de la Polic\u00eda Argentina, de la Provincia de Buenos Aires, aqu\u00ed varado, lo cual es muy llamativo\u00bb, cont\u00f3 el fiscal Marcelo Pecci, quien dio la orden del allanamiento a los agentes Contra el Crimen Organizado de la Polic\u00eda Nacional paraguaya.<\/p>\n\n\n\n<p>El operativo fue realizado esta tarde en el aer\u00f3dromo Array\u00e1n, ubicado a un poco m\u00e1s de 20 kil\u00f3metros de Asunci\u00f3n, donde la sorpresa fue ver el helic\u00f3ptero con el ploteo azul, verde y blanco de la Polic\u00eda Bonaerense y la inscripci\u00f3n Ministerio de Seguridad Buenos Aires Provincia. La nave era un Robinson R44.<\/p>\n\n\n\n<p>Tras conocerse el allanamiento, ex funcionarios de la gesti\u00f3n de Mar\u00eda Eugenia Vidal en la gobernaci\u00f3n de la Provincia se\u00f1alaron que ese helic\u00f3ptero \u00abhab\u00eda sido alquilado para el Operativo Sol 2019\/2020\u00bb y que desde entonces quedaron \u00abalojados en ese hangar\u00bb.<\/p>\n\n\n\n<p>\u00abResulta bastante llamativo tener una aeronave de una fuerza de seguridad extranjera aqu\u00ed. Hay algunas aeronaves que tienen ploteados finalizando las matr\u00edculas, lo cual est\u00e1 incumpliendo el reglamento\u00bb, consider\u00f3 el fiscal paraguayo.<\/p>\n\n\n\n<p>\u00abEstamos incautando los documentos y otros elementos que puedan ser \u00fatiles para clarificar cualquier tipo de il\u00edcito\u00bb, agreg\u00f3 Pecci a la televisi\u00f3n local y adelant\u00f3 que la Direcci\u00f3n Nacional de Aeron\u00e1utica Civil quedar\u00eda a cargo de \u00abrecabar uno a uno los datos de cada aeronave y las condiciones t\u00e9cnicas en las que se encuentran y eventualmente los permisos que correspondan\u00bb.<\/p>\n\n\n\n<p>Hasta el momento, y luego del allanamiento, hay dos detenidos que ser\u00e1n indagados en las pr\u00f3ximas horas por los fiscales intervinientes. Los peritajes avanzar\u00e1n en el aspirado de los fuselajes de cada uno de los aviones para tratar de detectar part\u00edculas de estupefacientes como coca\u00edna y marihuana.<\/p>\n\n\n\n<p>La Justicia tambi\u00e9n investigar\u00e1 si en el aer\u00f3dromo se dedican al hangaraje o tareas de reparaci\u00f3n, aunque Pecci sostuvo que \u00abindependientemente de eso tienen que estar en debidas condiciones las aeronaves, y si son extranjeras tienen que tener un permiso\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un helic\u00f3ptero que hab\u00eda sido alquilado por el\u00a0Ministerio de Seguridad bonaerense\u00a0durante la gesti\u00f3n de Mar\u00eda Eugenia Vidal fue allanado en la ciudad paraguaya de Aregu\u00e1 en el marco de una investigaci\u00f3n contra un grupo criminal vinculado al tr\u00e1fico de drogas por v\u00eda a\u00e9rea. \u00abEncontramos ocho aeronaves m\u00e1s un helic\u00f3ptero de la Polic\u00eda Argentina, de la &hellip;<\/p>\n","protected":false},"author":2,"featured_media":13763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50,8],"tags":[],"class_list":["post-13762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-judiciales","category-policiales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/10\/bccfaa9d-2511-44a7-b8ee-cceb4777165e.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13762"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13762\/revisions"}],"predecessor-version":[{"id":13764,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13762\/revisions\/13764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/13763"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}