{"id":13488,"date":"2020-10-03T16:12:33","date_gmt":"2020-10-03T19:12:33","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=13488"},"modified":"2020-10-03T16:12:36","modified_gmt":"2020-10-03T19:12:36","slug":"investigan-en-la-morgue-del-perrando-sobre-lo-ocurrido-con-un-paciente-fallecido-de-las-brenas","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/10\/03\/investigan-en-la-morgue-del-perrando-sobre-lo-ocurrido-con-un-paciente-fallecido-de-las-brenas\/","title":{"rendered":"Investigan en la morgue del Perrando sobre lo ocurrido con un paciente fallecido de Las Bre\u00f1as"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Ministerio de Salud P\u00fablica de la provincia, a trav\u00e9s de la Subsecretar\u00eda de Salud, informa que ya se encuentra iniciada la informaci\u00f3n sumaria para determinar lo sucedido en el caso de la entrega de un cuerpo equivocado a familiares de un paciente fallecido en el Hospital Perrando. El hecho sucedi\u00f3 ayer viernes 2 de octubre por la tarde en Las Bre\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la cartera aclararon que ni bien se recibi\u00f3 informaci\u00f3n del caso, desde la administraci\u00f3n central se procedi\u00f3 a las averiguaciones correspondientes, adem\u00e1s se tom\u00f3 contacto con los familiares y durante la ma\u00f1ana de este s\u00e1bado se encuentra siendo trasladado el cuerpo de la familiar fallecida en Resistencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo directivo del Hospital Perrando solicit\u00f3 un informe detallado de la morgue, el personal que se encontraba trabajando en el momento y el procedimiento de entrega de los cuerpos. Al respecto, aclararon que debido a la gravedad de la situaci\u00f3n se precedi\u00f3 a la investigaci\u00f3n de inmediato, para avanzar en la individualizaci\u00f3n de el o los responsables para aplicar las medidas disciplinarias correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Salud y el Hospital Perrando se pusieron a disposici\u00f3n de los familiares, realizando un pedido de disculpas personal y p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Salud P\u00fablica de la provincia, a trav\u00e9s de la Subsecretar\u00eda de Salud, informa que ya se encuentra iniciada la informaci\u00f3n sumaria para determinar lo sucedido en el caso de la entrega de un cuerpo equivocado a familiares de un paciente fallecido en el Hospital Perrando. El hecho sucedi\u00f3 ayer viernes 2 de &hellip;<\/p>\n","protected":false},"author":2,"featured_media":13489,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,46],"tags":[],"class_list":["post-13488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-salud"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/10\/NUEQJEINWNFFZF7RQM6YLHYHIA.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13488"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13488\/revisions"}],"predecessor-version":[{"id":13490,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13488\/revisions\/13490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/13489"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}