{"id":12728,"date":"2020-09-16T19:00:00","date_gmt":"2020-09-16T22:00:00","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=12728"},"modified":"2020-09-16T19:00:04","modified_gmt":"2020-09-16T22:00:04","slug":"el-gobierno-lanzo-una-linea-de-creditos-para-refaccionar-viviendas-y-motorizar-el-comercio-local","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/09\/16\/el-gobierno-lanzo-una-linea-de-creditos-para-refaccionar-viviendas-y-motorizar-el-comercio-local\/","title":{"rendered":"El gobierno lanz\u00f3 una l\u00ednea de cr\u00e9ditos para refaccionar viviendas y motorizar el comercio local"},"content":{"rendered":"\n<p>El gobernador Jorge Capitanich firm\u00f3 este mi\u00e9rcoles un convenio con el Instituto de Desarrollo Urbano y Vivienda (IPDUV) y con intendentes de once municipios que pondr\u00e1 en marcha un programa de asistencia financiera para refacci\u00f3n de viviendas, destinado a familias con imposibilidad econ\u00f3mica de acceder a pr\u00e9stamos bancarios de otras l\u00edneas.<\/p>\n\n\n\n<p>Prev\u00e9 una inversi\u00f3n de $150 millones por parte del Gobierno provincial y asistencia directa de hasta $154.000 para 1.000 titulares. Los beneficiarios devolver\u00e1n el 30% en 36 cuotas sin inter\u00e9s, mientras que el restante 70% ser\u00e1 amortizado por el IPDUV en concepto de subsidio y en articulaci\u00f3n con el Nuevo Banco del Chaco.<\/p>\n\n\n\n<p>\u201cEs una operatoria importante, tenemos distintas l\u00edneas de financiamiento para dar soluciones habitacionales dignas y seguridad jur\u00eddica a las familias chaque\u00f1as\u201d, asegur\u00f3 el gobernador, se\u00f1alando adem\u00e1s que \u201clos intendentes ser\u00e1n quienes certifiquen la necesidad de refacci\u00f3n de las viviendas\u201d.<\/p>\n\n\n\n<p>\u201cNos hemos fijado prioridades y una de ellas es generar estrategias que garanticen cobertura e inclusi\u00f3n social, como este programa de viviendas, que le da trabajo al ladrillero, al alba\u00f1il, al electricista\u201d, dijo Capitanich, y en esa l\u00ednea destac\u00f3: \u201cel 100% de la construcci\u00f3n se hace con insumos nacionales y de ese 100%, el 70% podemos producirlo en la provincia\u201d.<\/p>\n\n\n\n<p>Para la compra, los fondos ser\u00e1n depositados en una tarjeta TUYA y los beneficiarios podr\u00e1n adquirir los materiales en los m\u00e1s de 700 comercios adheridos. \u201cNo s\u00f3lo buscamos soluci\u00f3n habitacional, sino tambi\u00e9n motorizar el comercio local y generar empleo en la zona\u201d, indic\u00f3 por su parte el titular del IPDUV, Diego Ar\u00e9valo.<\/p>\n\n\n\n<p>Los requisitos de acceso son m\u00ednimos y tienen que ver con tener un \u00fanico inmueble registrado para la refacci\u00f3n o mejora, acreditar la precariedad habitacional con fotos, no registrar mora con el IPDUV y fotocopia de DNI. \u201cDeber\u00e1n presentar un documento que acredite la propiedad, ya sea t\u00edtulo, boleta de compra venta, comodato, constancia de tenencia otorgada por autoridad pertinente, u otro. Adem\u00e1s de un presupuesto de mano de obra de un t\u00e9cnico aprobado por la bolsa de empleo\u201d, detall\u00f3 Ar\u00e9valo.<\/p>\n\n\n\n<p>Acompa\u00f1aron tambi\u00e9n el secretario de Infraestructura y Servicios P\u00fablicos, Juan Manuel Carreras, y las intendentas y los intendentes de Barranqueras, Magda Ayala; de Fontana, Patricia Rodas; de Makall\u00e9, Marcelo Angione; de Laguna Blanca, Jos\u00e9 Panzardi; de Colonia Ben\u00edtez, Sergio Phipps; de Basail, Ignacio Rostan; de Margarita Bel\u00e9n, Javier Mart\u00ednez; de Puerto Tirol, Humberto De Pompert; y de Puerto Vilelas, V\u00edctor Rea.<\/p>\n\n\n\n<p>Anteriormente el programa se present\u00f3 en Las Garcitas, Quitilipi, Colonia Elisa, Charadai, Lapachito, La verde, Capit\u00e1n Solari, Co Telai, La Escondida, Machagai y Presidencia La Plaza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Jorge Capitanich firm\u00f3 este mi\u00e9rcoles un convenio con el Instituto de Desarrollo Urbano y Vivienda (IPDUV) y con intendentes de once municipios que pondr\u00e1 en marcha un programa de asistencia financiera para refacci\u00f3n de viviendas, destinado a familias con imposibilidad econ\u00f3mica de acceder a pr\u00e9stamos bancarios de otras l\u00edneas. Prev\u00e9 una inversi\u00f3n de &hellip;<\/p>\n","protected":false},"author":2,"featured_media":12729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5],"tags":[],"class_list":["post-12728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/09\/6c5e09419610ef2dab27fc249018891f.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=12728"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12728\/revisions"}],"predecessor-version":[{"id":12730,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12728\/revisions\/12730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12729"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=12728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=12728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=12728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}