{"id":11858,"date":"2020-08-27T00:41:37","date_gmt":"2020-08-27T03:41:37","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=11858"},"modified":"2020-08-27T02:17:42","modified_gmt":"2020-08-27T05:17:42","slug":"capitanich-firmo-convenio-con-nacion-para-fortalecer-el-sistema-sanitario","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2020\/08\/27\/capitanich-firmo-convenio-con-nacion-para-fortalecer-el-sistema-sanitario\/","title":{"rendered":"Capitanich firm\u00f3 convenio con Naci\u00f3n para fortalecer el sistema sanitario"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobernador Jorge Capitanich, en teleconferencia con el Ministro de Salud de la Naci\u00f3n Gin\u00e9s Gonz\u00e1lez Garc\u00eda, firm\u00f3 un acuerdo de articulaci\u00f3n con el Instituto de Seguridad Social, Seguros y Pr\u00e9stamos (INSSSEP) y el Ministerio de Salud P\u00fablica de la Provincia del Chaco.&nbsp;&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"550\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/8703c8df45aaf673f5623e30c5c2af0f.jpg\" alt=\"\" class=\"wp-image-11861\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/8703c8df45aaf673f5623e30c5c2af0f.jpg 850w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/8703c8df45aaf673f5623e30c5c2af0f-300x194.jpg 300w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/8703c8df45aaf673f5623e30c5c2af0f-768x497.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario chaque\u00f1o celebr\u00f3 la firma del convenio y se\u00f1al\u00f3 que representa el primer paso \u201cpara seguir fortaleciendo el sistema de una estrategia de coordinaci\u00f3n federal que sea equitativa y promueva las mejoras en la calidad de atenci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento establece la articulaci\u00f3n entre los subsectores del sistema sanitario a fin de brindar accesibilidad equitativa a servicios de salud de calidad y abordando como ejes la cobertura prestacional, el modelo asistencial, estrategias de financiamiento y la agenda de salud digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTendremos calidad cuando tengamos insumos, equipamientos, recursos humanos calificados, salarios dignos y mejor organizaci\u00f3n y coordinaci\u00f3n. Y cuando seamos capaces de recuperar erogaciones que significan subsidios encubiertos al sector privado que en definitiva acumulan excedentes que no les corresponden\u201d, enfatiz\u00f3 Capitanich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministro de Salud de la Naci\u00f3n, Gin\u00e9s Gonz\u00e1lez Garc\u00eda, asegur\u00f3 que \u201caprovechamos la pandemia para la innovaci\u00f3n. La salud nos ha unido y ha logrado cosas que otros sectores a veces no logran\u201d, sostuvo el funcionario, a la vez que consider\u00f3 que \u201cen un pa\u00eds federal hemos logrado unidad pol\u00edtica en la acci\u00f3n y compromiso conjunto y creo que tenemos que seguir as\u00ed por el per\u00edodo que falta\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la firma particip\u00f3 la ministra de Salud P\u00fablica de la provincia, Paola Ben\u00edtez, el presidente del INSSSEP, Antonio Morante, el Jefe de Gabinete del Ministerio de Salud de la Naci\u00f3n, Lisandro Bonelli y el Secretario de Equidad de la cartera sanitaria Nacional, Mart\u00edn Sabignoso. Por parte de las provincias, estuvieron presentes los gobernadores de Santa Fe, Omar Perotti; de San Juan, Sergio U\u00f1ac; de San Luis, Alberto Rodr\u00edguez Saa y de Tierra del Fuego, Gustavo Melella.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/portalmovil.com.ar\/index.php\/suscripciones\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"123\" src=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/suscripciones-PM-1024x123-1-48.png\" alt=\"\" class=\"wp-image-10982\" srcset=\"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/suscripciones-PM-1024x123-1-48.png 1024w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/suscripciones-PM-1024x123-1-48-300x36.png 300w, https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/suscripciones-PM-1024x123-1-48-768x92.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Jorge Capitanich, en teleconferencia con el Ministro de Salud de la Naci\u00f3n Gin\u00e9s Gonz\u00e1lez Garc\u00eda, firm\u00f3 un acuerdo de articulaci\u00f3n con el Instituto de Seguridad Social, Seguros y Pr\u00e9stamos (INSSSEP) y el Ministerio de Salud P\u00fablica de la Provincia del Chaco.&nbsp;&nbsp; El mandatario chaque\u00f1o celebr\u00f3 la firma del convenio y se\u00f1al\u00f3 que representa &hellip;<\/p>\n","protected":false},"author":2,"featured_media":11883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,46,12],"tags":[],"class_list":["post-11858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaco","category-salud","category-ultimo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2020\/08\/d9e08d8cf3c14836af95f234f548235c.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11858"}],"version-history":[{"count":2,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11858\/revisions"}],"predecessor-version":[{"id":11862,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11858\/revisions\/11862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11883"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}