{"id":113473,"date":"2025-10-09T20:27:16","date_gmt":"2025-10-09T23:27:16","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=113473"},"modified":"2025-10-09T20:27:18","modified_gmt":"2025-10-09T23:27:18","slug":"liberaron-una-yaguarete-en-el-parque-nacional-el-impenetrable","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2025\/10\/09\/liberaron-una-yaguarete-en-el-parque-nacional-el-impenetrable\/","title":{"rendered":"Liberaron una yaguaret\u00e9 en el parque Nacional El Impenetrable"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El regreso del yaguaret\u00e9 al Chaco Argentino sigue progresando con la liberaci\u00f3n de una quinta hembra en el Parque Nacional El Impenetrable. Se trata de Aca\u00ed, una hembra silvestre nacida en el Iber\u00e1. El hito trae esperanzas para la escasa poblaci\u00f3n de yaguaret\u00e9s del Impenetrable que, compuesta s\u00f3lo por machos dispersantes, estaba destinada a la extinci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta liberaci\u00f3n se concret\u00f3 apenas unos d\u00edas despu\u00e9s del anuncio de la iniciativa R\u00edos del Yaguaret\u00e9 (Jaguar Rivers Initiative), que busca salvar el yaguaret\u00e9 y restaurar ecosistemas en Argentina, Brasil, Paraguay y Bolivia, marcando un nuevo cap\u00edtulo en la recuperaci\u00f3n de esta especie emblem\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aca\u00ed, una yaguaret\u00e9 nacida en libertad en el Parque Nacional Iber\u00e1, se ha unido a las otras hembras liberadas en el Parque Nacional El Impenetrable, para intentar recuperar la especie en el Gran Chaco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El regreso del yaguaret\u00e9 al Chaco Argentino sigue progresando con la liberaci\u00f3n de una quinta hembra en el Parque Nacional El Impenetrable. Se trata de Aca\u00ed, una hembra silvestre nacida en el Iber\u00e1. El hito trae esperanzas para la escasa poblaci\u00f3n de yaguaret\u00e9s del Impenetrable que, compuesta s\u00f3lo por machos dispersantes, estaba destinada a la &hellip;<\/p>\n","protected":false},"author":2,"featured_media":113474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28,5],"tags":[],"class_list":["post-113473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-chaco"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2025\/10\/Yaguarete-LiberanAcai1.png","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/113473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=113473"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/113473\/revisions"}],"predecessor-version":[{"id":113475,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/113473\/revisions\/113475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/113474"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=113473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=113473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=113473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}