{"id":104295,"date":"2024-12-02T12:34:10","date_gmt":"2024-12-02T15:34:10","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=104295"},"modified":"2024-12-02T12:34:13","modified_gmt":"2024-12-02T15:34:13","slug":"pami-redefine-acceso-a-medicamentos-gratuitos-requisitos-e-implementacion","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/12\/02\/pami-redefine-acceso-a-medicamentos-gratuitos-requisitos-e-implementacion\/","title":{"rendered":"PAMI redefine acceso a medicamentos gratuitos: requisitos e implementaci\u00f3n"},"content":{"rendered":"\n<p>El Instituto Nacional de Servicios Sociales para Jubilados y Pensionados (PAMI) anunci\u00f3 cambios en las condiciones para que sus afiliados accedan a la cobertura del 100% en medicamentos. Estas modificaciones estar\u00e1n vigentes para los jubilados chaque\u00f1os y de todo el pa\u00eds, quienes deber\u00e1n realizar un tr\u00e1mite espec\u00edfico para mantener el beneficio.<\/p>\n\n\n\n<p>NUEVOS REQUISITOS PARA LA COBERTURA TOTAL:\u00a0<\/p>\n\n\n\n<p>Los afiliados interesados en mantener el reintegro completo deber\u00e1n cumplir con las siguientes condiciones:<\/p>\n\n\n\n<p>Percibir ingresos de hasta una jubilaci\u00f3n y media m\u00ednima (o tres haberes previsionales en caso de convivir con una persona con Certificado \u00danico de Discapacidad).<br>No estar afiliados a una obra social o medicina prepaga.<\/p>\n\n\n\n<p>No poseer m\u00e1s de un inmueble, veh\u00edculos con menos de 10 a\u00f1os de antig\u00fcedad ni bienes de lujo.<br>No tener activos societarios que evidencien capacidad econ\u00f3mica plena.<br>En casos excepcionales, si el costo de los medicamentos equivale al 15% o m\u00e1s de los ingresos del afiliado, se podr\u00e1 solicitar la cobertura mediante un tr\u00e1mite especial.<\/p>\n\n\n\n<p>PAMI inst\u00f3 a sus afiliados chaque\u00f1os y de todo el pa\u00eds a realizar el tr\u00e1mite correspondiente para no perder la cobertura y estar informados sobre las nuevas condiciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Nacional de Servicios Sociales para Jubilados y Pensionados (PAMI) anunci\u00f3 cambios en las condiciones para que sus afiliados accedan a la cobertura del 100% en medicamentos. Estas modificaciones estar\u00e1n vigentes para los jubilados chaque\u00f1os y de todo el pa\u00eds, quienes deber\u00e1n realizar un tr\u00e1mite espec\u00edfico para mantener el beneficio. NUEVOS REQUISITOS PARA LA &hellip;<\/p>\n","protected":false},"author":2,"featured_media":74699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[639,46],"tags":[],"class_list":["post-104295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-salud"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2023\/04\/medicamentos_pami_1.jpg_1402874324.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/104295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=104295"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/104295\/revisions"}],"predecessor-version":[{"id":104296,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/104295\/revisions\/104296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/74699"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=104295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=104295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=104295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}