{"id":101755,"date":"2024-09-18T18:41:03","date_gmt":"2024-09-18T21:41:03","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=101755"},"modified":"2024-09-18T18:41:05","modified_gmt":"2024-09-18T21:41:05","slug":"inspectores-lo-descubrieron-tirando-basura-a-bordo-de-un-carro-con-traccion-a-sangre","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/09\/18\/inspectores-lo-descubrieron-tirando-basura-a-bordo-de-un-carro-con-traccion-a-sangre\/","title":{"rendered":"Inspectores lo descubrieron tirando basura a bordo de un carro con tracci\u00f3n a sangre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Municipalidad de Resistencia sigue firme en su lucha contra la proliferaci\u00f3n de basurales espont\u00e1neos en la v\u00eda p\u00fablica y la erradicaci\u00f3n de la circulaci\u00f3n de carros tirados por tracci\u00f3n a sangre animal en la ciudad. Esta tarea se lleva adelante a partir de la aplicaci\u00f3n de sanciones que van desde multas hasta el secuestro del veh\u00edculo y la detenci\u00f3n del conductor por el maltrato del animal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco de dichos controles, personal detect\u00f3 en la zona de Leandro N. Alem al 2510, un ciudadano a bordo de un carro; el que se encontraba arrojando basura en la v\u00eda p\u00fablica y fue identificado por inspectores de Tr\u00e1nsito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los agentes solicitaron la intervenci\u00f3n del coordinador del programa, Cristian Aguirre, quien bajo la \u00f3rbita de la Subsecretar\u00eda de Gesti\u00f3n Ambiental inform\u00f3 a la Comisar\u00eda jurisdiccional y a la Polic\u00eda Rural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la Subsecretar\u00eda de Tr\u00e1nsito y Transporte recordaron que el Art\u00edculo 176, inciso H, de la Ordenanza municipal establece la remoci\u00f3n de veh\u00edculos usados para arrojar residuos patol\u00f3gicos; por lo cual instan a la ciudadan\u00eda a denunciar a los infractores ambientales a trav\u00e9s del WhatsApp 3624734364.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Resistencia sigue firme en su lucha contra la proliferaci\u00f3n de basurales espont\u00e1neos en la v\u00eda p\u00fablica y la erradicaci\u00f3n de la circulaci\u00f3n de carros tirados por tracci\u00f3n a sangre animal en la ciudad. Esta tarea se lleva adelante a partir de la aplicaci\u00f3n de sanciones que van desde multas hasta el secuestro &hellip;<\/p>\n","protected":false},"author":2,"featured_media":101756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,37],"tags":[],"class_list":["post-101755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-resistencia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/09\/basura-carro.jpeg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/101755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=101755"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/101755\/revisions"}],"predecessor-version":[{"id":101757,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/101755\/revisions\/101757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/101756"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=101755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=101755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=101755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}