{"id":101042,"date":"2024-09-03T22:17:57","date_gmt":"2024-09-04T01:17:57","guid":{"rendered":"https:\/\/portalmovil.com.ar\/?p=101042"},"modified":"2024-09-03T22:18:00","modified_gmt":"2024-09-04T01:18:00","slug":"un-intendente-de-corrientes-gana-6-millones-por-mes-y-los-empleados-municipales-70-mil","status":"publish","type":"post","link":"https:\/\/portalmovil.com.ar\/index.php\/2024\/09\/03\/un-intendente-de-corrientes-gana-6-millones-por-mes-y-los-empleados-municipales-70-mil\/","title":{"rendered":"Un Intendente de Corrientes gana $6 millones por mes y los empleados municipales $70 mil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Concejales de la oposici\u00f3n denuncian al intendente Jos\u00e9 Augusto Suaid por presunta malversaci\u00f3n de fondos y exigen transparencia en la gesti\u00f3n municipal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la localidad correntina de<strong>&nbsp;Santo Tom\u00e9<\/strong>, una controversia salarial ha desatado un&nbsp;<strong>esc\u00e1ndalo pol\u00edtico&nbsp;<\/strong>que involucra al intendente&nbsp;<strong>Jos\u00e9 Augusto Suaid<\/strong>. Seg\u00fan&nbsp;<strong>denuncias&nbsp;<\/strong>de&nbsp;<strong>concejales opositores<\/strong>, el jefe comunal<strong>&nbsp;se habr\u00eda aumentado su salario a aproximadamente 6 millones de pesos mensuales, mientras que los empleados municipales de menor rango perciben entre 70 y 120 mil pesos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El concejal&nbsp;<strong>Pablo Leguiza<\/strong>, en declaraciones a Radio Nordeste, afirm\u00f3: \u00ab<strong>\u00c9l hoy estar\u00eda cobrando aproximadamente 6 millones de pesos, porque no \u00fanicamente cobra los 12 sueldos b\u00e1sicos de la \u00faltima categor\u00eda, sino tambi\u00e9n&nbsp;el 100% de su representaci\u00f3n m\u00e1s todas las bonificaciones que tenga<\/strong>\u00ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Este aumento salarial se habr\u00eda producido a partir de la aprobaci\u00f3n de una nueva carta org\u00e1nica municipal en mayo de este a\u00f1o<\/strong>, que entr\u00f3 en vigencia el 1 de junio.&nbsp;<strong>Leguiza se\u00f1al\u00f3 que antes de esta modificaci\u00f3n, el sueldo del intendente era de 500 mil pesos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n ha generado indignaci\u00f3n entre los concejales de la oposici\u00f3n, quienes han solicitado reiteradamente informaci\u00f3n detallada sobre los salarios de los empleados municipales. \u00ab<strong>Venimos pidiendo la lista de trabajadores municipales para poder tener una informaci\u00f3n concreta, una lista detallada con las categor\u00edas<\/strong>\u00ab, explic\u00f3 Leguiza. Sin embargo, estas solicitudes habr\u00edan sido archivadas o ignoradas por ser minor\u00eda en el Concejo Deliberante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La disparidad salarial es notable:&nbsp;<strong>mientras el intendente percibir\u00eda 6 millones de pesos, los concejales cobran alrededor de 680 mil pesos, y los empleados de menor rango entre 70 y 120 mil pesos<\/strong>. \u00abLos&nbsp;<strong>becarios&nbsp;<\/strong>y&nbsp;<strong>jornaleros<\/strong>&nbsp;cobran entre&nbsp;<strong>$70.000 y $120.000<\/strong>\u00ab, afirm\u00f3 Leguiza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esta situaci\u00f3n, los concejales opositores han decidido llevar el caso a la justicia. \u00ab<strong>Ayer hicimos una presentaci\u00f3n judicial en Fiscal\u00eda<\/strong>\u00ab, revel\u00f3 Leguiza, agregando que \u00ab<strong>se pide que se empiecen a investigar a ra\u00edz de la denuncia de la semana pasada que ha hecho una proveedora<\/strong>\u00ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La denuncia no solo abarca la cuesti\u00f3n salarial, sino que tambi\u00e9n incluye sospechas de irregularidades en la administraci\u00f3n municipal y en la relaci\u00f3n con proveedores. \u00ab<strong>Venimos viendo irregularidades, esto de no compartir la informaci\u00f3n, de no acercarnos las planillas de los trabajadores, acercarnos a un balance cuatrimestral de documentos<\/strong>\u00ab, explic\u00f3 el concejal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concejales de la oposici\u00f3n denuncian al intendente Jos\u00e9 Augusto Suaid por presunta malversaci\u00f3n de fondos y exigen transparencia en la gesti\u00f3n municipal En la localidad correntina de&nbsp;Santo Tom\u00e9, una controversia salarial ha desatado un&nbsp;esc\u00e1ndalo pol\u00edtico&nbsp;que involucra al intendente&nbsp;Jos\u00e9 Augusto Suaid. Seg\u00fan&nbsp;denuncias&nbsp;de&nbsp;concejales opositores, el jefe comunal&nbsp;se habr\u00eda aumentado su salario a aproximadamente 6 millones de pesos &hellip;<\/p>\n","protected":false},"author":2,"featured_media":101043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[639,14],"tags":[],"class_list":["post-101042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-politica"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/portalmovil.com.ar\/wp-content\/uploads\/2024\/09\/795856_grande.jpg","_links":{"self":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/101042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=101042"}],"version-history":[{"count":1,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/101042\/revisions"}],"predecessor-version":[{"id":101044,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/101042\/revisions\/101044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media\/101043"}],"wp:attachment":[{"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=101042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=101042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalmovil.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=101042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}